{"id":203246,"date":"2023-05-31T19:19:13","date_gmt":"2023-05-31T17:19:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203246"},"modified":"2023-05-31T19:19:13","modified_gmt":"2023-05-31T17:19:13","slug":"diamante-domani-un-minuto-di-silenzio-per-ricordare-la-giovane-denise","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/diamante-domani-un-minuto-di-silenzio-per-ricordare-la-giovane-denise\/","title":{"rendered":"Diamante, domani un minuto di silenzio per ricordare la giovane Denise"},"content":{"rendered":"<p>DIAMANTE (CS) &#8211; Domani a Diamante sar\u00e0 osservato un minuto di silenzio per ricordare la\u00a0 giovane Denise Galat\u00e0, la 19enne <strong><a href=\"https:\/\/quicosenza.it\/news\/provincia\/trovato-il-corpo-senza-vita-di-denise-dopo-ore-di-ricerche-il-tragico-epilogo\" target=\"_blank\" rel=\"noopener\">ritrovata senza vita<\/a><\/strong> oggi nel fiume Lao a Laino Borgo.<\/p>\n<p>&#8220;L&#8217;Amministrazione Comunale \u2013 rende noto il Vicesindaco Giuseppe Pascale \u2013 invita gli uffici pubblici e privati, gli esercizi commerciali e tutta la cittadinanza a<strong> fermarsi, alle ore 12, per un minuto di raccoglimento<\/strong> per la studentessa del Liceo Rechichi di Polistena scomparsa in seguito alla caduta nel Fiume Lao durante una gita scolastica.<\/p>\n<p style=\"font-weight: 400;\">Nel primo pomeriggio l&#8217;Amministrazione Comunale aveva espresso il suo cordoglio sui suoi canali social:<\/p>\n<p>&#8220;La Citt\u00e0 di Diamante si unisce al <strong>profondo cordoglio<\/strong> di tutta la Calabria per la scomparsa di <strong>Denise Galat\u00e0<\/strong>, la studentessa del Liceo Rechichi di Polistena scomparsa in seguito alla caduta nel Fiume Lao durante una gita scolastica.<\/p>\n<p>Ai familiari e ai compagni di Denise giunga la vicinanza e l&#8217;abbraccio di tutta la comunit\u00e0 di Diamante&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIAMANTE (CS) &#8211; Domani a Diamante sar\u00e0 osservato un minuto di silenzio per ricordare la\u00a0 giovane Denise Galat\u00e0, la 19enne ritrovata senza vita oggi nel fiume Lao a Laino Borgo. &#8220;L&#8217;Amministrazione Comunale \u2013 rende noto il Vicesindaco Giuseppe Pascale \u2013 invita gli uffici pubblici e privati, gli esercizi commerciali e tutta la cittadinanza a fermarsi, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":203225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-203246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203246"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/203225"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}