{"id":20327,"date":"2013-03-28T11:55:39","date_gmt":"2013-03-28T10:55:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20327"},"modified":"2023-01-17T13:18:07","modified_gmt":"2023-01-17T12:18:07","slug":"7692-droga-da-napoli-a-catanzaro-6-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7692-droga-da-napoli-a-catanzaro-6-arresti\/","title":{"rendered":"Droga: da Napoli a Catanzaro, 6 arresti"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; L&#8217; operazione denominata &#8221; The Wall&#8221;, si \u00e8 conclusa con sei condanne a pene comprese fra i 14 e i 2 anni di reclusione il giudizio abbreviato<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">a carico di altrettanti imputati coinvolti in un&#8217;organizzazione dedita al narcotraffico operativa a Catanzaro e con canale di approvvigionamento a Napoli. Il giudice distrettuale dell&#8217;udienza preliminare di Catanzaro, Livio Sabatini, ha accolto le richieste formulate all&#8217;udienza del 14 novembre scorso dal pubblico ministero, Elio Romano, infliggendo pene di poco diverse di quelle sollecitate dalla Procura antimafia, ed ha condannato Alessandro Critelli a 14 anni e 8 mesi di reclusione (il pm aveva chiesto 16 anni di reclusione); la moglie di quest&#8217;ultimo, Maria Passalacqua, a 8 anni (chiesti 14 anni); Giuseppe Lazzarini a 8 anni e 4 mesi (chiesti 8 anni); Domenico Chirumbolo e Antonio Giudice a 4 anni 5 mesi e 10 giorni ciascuno (chiesti 4 anni e 8 mesi ciascuno); Ivan Manfredi a 2 anni e 8 mesi e 14.600 euro (chiesti 3 anni e 4 mesi e 16.000 euro di multa). Le pene sono cosi&#8217; scontate di un terzo per la scelta del rito alternativo al dibattimento.<\/p>\n<p style=\"text-align: justify;\">Per le altre sei persone coinvolte nella medesima inchiesta antidroga, tra le quali il carabiniere Giuseppe Maranzano, 46 anni, in pensione, accusato di corruzione perche&#8217; secondo gli inquirenti avrebbe garantito, attraverso il suo ruolo di militare in servizio nel capoluogo calabrese, controlli meno asfissianti nei confronti di un sorvegliato speciale, e&#8217; in corso il processo davanti al tribunale collegiale di Catanzaro dopo che il giudice per le indagini preliminari ha accolto la richiesta di giudizio immediato avanzata dall&#8217;Ufficio di procura.<\/p>\n<p style=\"text-align: justify;\">Gli imputati sono stati destinatari di un&#8217;ordinanza cautelare, eseguita all&#8217;alba del 29 marzo dalla Squadra mobile di Catanzaro con il blitz &#8220;The Wall&#8221;, che ha portato in carcere quattro persone, agli arresti domiciliari altre sette, e una all&#8217;obbligo di dimora. Secondo l&#8217;accusa la banda di trafficanti era riuscita a monopolizzare lo spaccio di sostanze stupefacenti &#8211; eroina, cocaina, crack e kobrett -, acquistate a Napoli e portate nel capoluogo calabrese dai corrieri del gruppo, anche grazie alla partecipazione di soggetti di etnia rom stanziali da anni ormai sul territorio catanzarese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; L&#8217; operazione denominata &#8221; The Wall&#8221;, si \u00e8 conclusa con sei condanne a pene comprese fra i 14 e i 2 anni di reclusione il giudizio abbreviato<\/p>\n","protected":false},"author":22,"featured_media":20328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-20327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20327"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20328"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}