{"id":20353,"date":"2013-03-28T14:07:53","date_gmt":"2013-03-28T13:07:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20353"},"modified":"2023-01-17T13:18:09","modified_gmt":"2023-01-17T12:18:09","slug":"7705-pentito-camorra-clona-carte-di-credito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7705-pentito-camorra-clona-carte-di-credito\/","title":{"rendered":"Pentito camorra clona carte di credito"},"content":{"rendered":"<p><p><strong>MILANO<\/strong> &#8211; Un pentito di camorra si dilettava a clonare carte di credito. L&#8217;uomo \u00e8 stato scoperto mentre praticava nel Nord Italia, a capo di una banda specializzata nel clonare e utilizzare indebitamente carte di credito.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;indagine, realizzata dalla Polizia stradale di Milano, ha portato all&#8217;emissione di 6 ordinanze di custodia cautelare. L&#8217;uomo ha una nuova identita&#8217; e il mantenimento dello Stato.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILANO &#8211; Un pentito di camorra si dilettava a clonare carte di credito. L&#8217;uomo \u00e8 stato scoperto mentre praticava nel Nord Italia, a capo di una banda specializzata nel clonare e utilizzare indebitamente carte di credito.<\/p>\n","protected":false},"author":22,"featured_media":20354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-20353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20353"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20354"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}