{"id":203572,"date":"2023-06-05T17:40:29","date_gmt":"2023-06-05T15:40:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203572"},"modified":"2023-06-05T19:07:41","modified_gmt":"2023-06-05T17:07:41","slug":"riapre-il-ponte-bagni-che-collega-acquappesa-a-guardia-piemontese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/riapre-il-ponte-bagni-che-collega-acquappesa-a-guardia-piemontese\/","title":{"rendered":"Riapre il Ponte Bagni, che collega Acquappesa a Guardia Piemontese"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Il Ponte Bagni, che collega il Comune di Acquappesa a quello di Guardia Piemontese, \u00e8 nuovamente transitabile<\/strong> grazie a un accordo tra Provincia di Cosenza, Regione Calabria e le due cittadine del Tirreno cosentino.<\/p>\n<p>Il tratto fu chiuso nel mese di aprile dello scorso anno quando si verific\u00f2 un incidente stradale, che coinvolse un commerciante con conseguente\u00a0<strong>caduta dal ponte Bagni<\/strong>\u00a0<strong>da un\u2019altezza di circa dieci metri<\/strong> nel sottostante fiume.<\/p>\n<p>La riapertura del Ponte Bagni si inserisce tra altri due <strong>rilevanti interventi di ripristino della viabilit\u00e0 provinciale<\/strong>: sulla S.P. 29 per un importo pari a 800.000 euro, strada chiusa da diversi anni; e sulla S.P. 34, dove con uno stanziamento di 400.000 euro viene messo in sicurezza il costone roccioso.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Ponte Bagni, che collega il Comune di Acquappesa a quello di Guardia Piemontese, \u00e8 nuovamente transitabile grazie a un accordo tra Provincia di Cosenza, Regione Calabria e le due cittadine del Tirreno cosentino. Il tratto fu chiuso nel mese di aprile dello scorso anno quando si verific\u00f2 un incidente stradale, che coinvolse [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":203574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-203572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203572"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/203574"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}