{"id":203601,"date":"2023-06-06T09:00:24","date_gmt":"2023-06-06T07:00:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203601"},"modified":"2023-06-06T09:49:08","modified_gmt":"2023-06-06T07:49:08","slug":"belvedere-marittimo-cauteruccio-degrado-su-spiaggia-libera-strutture-ricettive","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/belvedere-marittimo-cauteruccio-degrado-su-spiaggia-libera-strutture-ricettive\/","title":{"rendered":"Belvedere Marittimo, Cauteruccio \u00abdegrado su spiaggia libera e strutture ricettive\u00bb"},"content":{"rendered":"<p>BELVEDERE MARITTIMO &#8211; &#8220;Nella qualit\u00e0 di consigliere comunale eletto dal popolo, ho <strong>raccolto le istanze dei cittadini, dei primi turisti e degli operatori del settore<\/strong>. La stagione estiva \u00e8 iniziata, e preso atto del rincaro dell&#8217;<strong>imposta di soggiorno<\/strong>, nonostante il voto contrario di Impegno Comune, riteniamo che l\u2019adeguamento dell&#8217;imposta sia avvenuta oltre tempo limite e che a questo punto <strong>potrebbe diventare un possibile deterrente per la promozione turistica.<\/strong> Al netto per\u00f2 delle valutazioni politiche, occorre fare una seria riflessione, partendo dal concetto che la <strong>qualit\u00e0 dei servizi<\/strong> non giustifica, ancora una vota, la richiesta di maggiori tasse da pagare. Quali sono i servizi che volete offrire e che in parte giustificano gli aumenti?&#8221;.<\/p>\n<p>Lo afferma l&#8217;Ing. <strong>Francesco Cauteruccio,<\/strong> consigliere comunale di opposizione membro del gruppo &#8220;<strong>Impegno Comune per Belvedere Marittimo&#8221;<\/strong>: &#8220;Le varie aree del territorio di Belvedere Marittimo, dove spiaggia libera e strutture ricettive dovrebbero accoglierci, sono accomunate da un unico comune denominatore: <strong>il degrado&#8221;<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203607 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 06\" width=\"562\" height=\"348\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-06-356x220.jpg 356w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><\/p>\n<p>&#8220;<strong>Accessi alla spiaggia libera ostruiti. Spiaggia libera sporca. Assenza di falcio dell&#8217;erba e di pulizia. Totale assenza di manutenzione<\/strong>. Evidenti fonti di pericolo generatesi dal degrado. Mancanza di <strong>strisce pedonali<\/strong> in corrispondenza dei sottopassi che consentono l\u2019accesso al mare. Abbandono e degrado caratterizzano le spiagge di Calabaia e <strong>fino al confine con Sangineto<\/strong>, dove \u00e8 sono stati necessari la realizzazione di frangiflutto ed un ripascimento per garantire la messa in sicurezza dell\u2019edificato. Quest\u2019arenile di cui oggi potrebbe gode l\u2019intera citt\u00e0, derivante dall\u2019intervento di ripascimento, dovrebbe essere al centro dell\u2019attenzione per il rilancio del turismo balneare, poich\u00e9 si tratta di un ambito territoriale, che ospita importanti strutture recettive e che urbanisticamente, per come previsto dal piano particolareggiato allegato al Piano Regolatore Generale, \u00e8 destinato alla sola realizzazione di strutture turistico&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203613 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica spiaggia\" width=\"517\" height=\"320\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-356x220.jpg 356w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><\/p>\n<p>&#8220;La <strong>situazione<\/strong> &#8211; prosegue Cauteruccio &#8211; <strong>non cambia<\/strong> se ci spostiamo a <strong>nord della marina di Belvedere;<\/strong>\u00a0basta osservare lo stato di degrado della pista sterrata interposta fra la ferrovia ed il mare, dell\u2019abbandono dei sottopassi, delle carenti condizioni igienico sanitarie, non si prevede una derattizzazione nonostante la presenza delle scogliere, non sono istallaci cestini per la raccolta dei rifiuti, non sono state ripristinate le doccette esistenti&#8221;.<\/p>\n<p>Cauteruccio pungola ancora la maggioranza del sindaco Cascini e chiede: &#8220;che cosa sta facendo il comune di Belvedere Marittimo? Dati Istat attestano con riferimento all&#8217;anno 2021 &#8211; addirittura in era segnata dal Covid &#8211; oltre <strong>18mila arrivi nelle strutture recettive<\/strong> di Belvedere Marittimo. Calcolando una media di \u20ac<strong> 1,75 euro<\/strong> al giorno per ciascun ospite e per ciascun giorno di permanenza, l&#8217;ente potrebbe arrivare a monetizzare oltre 30mila euro. Come intendete spendere questi soldi? Dal primo luglio sar\u00e0 attivo un servizio Navetta Gratuito sul quale mi riservo di intervenire in futuro, ma il sindaco e la sua maggioranza ritengono che possa bastare?&#8221;.<\/p>\n<p>Il consigliere comunale di Minoranza rende noto ancora: &#8220;Il comune di Belvedere Marittimo incasser\u00e0 <strong>oltre 30mila euro per imposta di soggiorno<\/strong> ma gli accessi alla spiaggia pubblica restano un tab\u00f9 per le persone con problemi motori e persino per i cittadini che debbono fare gli slalom tra erbacce e sporcizia. Eppure, impegno Comune aveva avvertito questa maggioranza. L&#8217;estate sta arrivando e ancora una volta rischiamo di non essere pronti. Questo accade &#8211; conclude Cauteruccio &#8211; quando ad una seria programmazione viene preferita l&#8217;approssimazione pi\u00f9 totale. Belvedere Marittimo merita di meglio&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203612 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica spiaggia 03\" width=\"558\" height=\"345\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-spiaggia-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 558px) 100vw, 558px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203610 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 09\" width=\"572\" height=\"354\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-09-356x220.jpg 356w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203609 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 08\" width=\"562\" height=\"348\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-08-356x220.jpg 356w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203608 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 07\" width=\"557\" height=\"344\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-07-356x220.jpg 356w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203606 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 05\" width=\"561\" height=\"347\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-05-356x220.jpg 356w\" sizes=\"auto, (max-width: 561px) 100vw, 561px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203605 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 04\" width=\"560\" height=\"347\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-04-356x220.jpg 356w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203604 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 03\" width=\"553\" height=\"342\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203603 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 02\" width=\"552\" height=\"341\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203602 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01.jpg\" alt=\"Belvedere marittimo - degrado per stagione turistica 01\" width=\"554\" height=\"343\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Belvedere-marittimo-degrado-per-stagione-turistica-01-356x220.jpg 356w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELVEDERE MARITTIMO &#8211; &#8220;Nella qualit\u00e0 di consigliere comunale eletto dal popolo, ho raccolto le istanze dei cittadini, dei primi turisti e degli operatori del settore. La stagione estiva \u00e8 iniziata, e preso atto del rincaro dell&#8217;imposta di soggiorno, nonostante il voto contrario di Impegno Comune, riteniamo che l\u2019adeguamento dell&#8217;imposta sia avvenuta oltre tempo limite e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":203611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-203601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203601"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/203611"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}