{"id":203701,"date":"2023-06-06T18:16:49","date_gmt":"2023-06-06T16:16:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203701"},"modified":"2023-06-06T18:22:57","modified_gmt":"2023-06-06T16:22:57","slug":"cosenza-in-arrivo-pc-per-le-scuole-dal-movimento-5-stelle","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-in-arrivo-pc-per-le-scuole-dal-movimento-5-stelle\/","title":{"rendered":"Cosenza, in arrivo pc per le scuole dal Movimento 5 Stelle"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Con il progetto &#8216;Facciamo scuola digitale&#8217; <strong>il Movimento 5 Stelle doner\u00e0 personal computer portatili anche agli istituti scolastici della provincia di Cosenza<\/strong> che hanno partecipato al concorso con la presentazione di specifici progetti&#8221;. Lo dichiara in una nota la deputata del Movimento 5 Stelle, Elisa Scutell\u00e0.<\/p>\n<p>&#8220;Le scuole che in questi giorni riceveranno i computer &#8211; prosegue &#8211; sono: l&#8217;Istituto comprensivo di Belvedere Marittimo,<strong> l&#8217;Istituto comprensivo Isidoro Gentili di Paola<\/strong>, <strong>l&#8217;Istituto di istruzione superiore Ite Cosentino<\/strong> &#8211;<strong> Ipaa Todaro di Rende e l&#8217;Istituto comprensivo G.B. Moscato di San Lucido<\/strong>. Dopo il grande successo di &#8216;Facciamo Ecoscuola&#8217;, iniziativa con la quale abbiamo destinato oltre 3 milioni di euro delle somme restituite dai parlamentari e consiglieri regionali del Movimento 5 Stelle al finanziamento di idee-progetti che promuovessero la sostenibilit\u00e0 e l&#8217;educazione ambientale in oltre 200 scuole pubbliche, con &#8216;Facciamo scuola digitale&#8217; investiamo <strong>1 milione di euro<\/strong> nelle scuole pubbliche&#8221;.<\/p>\n<p><strong>&#8220;Noi ai tagli alle scuole e all&#8217;istruzione &#8211; conclude Scutell\u00e0 &#8211; preferiamo gli investimenti<\/strong> quelli verso le nuove generazioni in controtendenza con ci\u00f2 che invece sta portando avanti questo governo: un&#8217;azione che incentiva la precariet\u00e0 e totalmente disinteressata al futuro del nostro Paese&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Con il progetto &#8216;Facciamo scuola digitale&#8217; il Movimento 5 Stelle doner\u00e0 personal computer portatili anche agli istituti scolastici della provincia di Cosenza che hanno partecipato al concorso con la presentazione di specifici progetti&#8221;. Lo dichiara in una nota la deputata del Movimento 5 Stelle, Elisa Scutell\u00e0. &#8220;Le scuole che in questi giorni riceveranno [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":117867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[19],"class_list":["post-203701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203701"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117867"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}