{"id":203735,"date":"2023-06-07T11:00:28","date_gmt":"2023-06-07T09:00:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203735"},"modified":"2023-06-07T09:35:05","modified_gmt":"2023-06-07T07:35:05","slug":"giornata-mondiale-sulla-sicurezza-alimentare-nas-sequestrate-8mila-tonnellate-di-alimenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giornata-mondiale-sulla-sicurezza-alimentare-nas-sequestrate-8mila-tonnellate-di-alimenti\/","title":{"rendered":"Giornata mondiale sulla sicurezza alimentare, Nas \u00absequestrate 8mila tonnellate di alimenti\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Oggi 7 giugno si celebra la \u201cGiornata mondiale della sicurezza alimentare\u201d, iniziativa internazionale istituita nel 2019 dall\u2019Organizzazione Mondiale della Sanit\u00e0 (OMS), dall\u2019Organizzazione delle Nazioni Unite per l\u2019alimentazione e l\u2019agricoltura (FAO) e CODEX Alimentarius e dal Ministero della Salute &#8211; Direzione Generale per l\u2019Igiene e la Sicurezza degli Alimenti e la Nutrizione (DGISAN).<\/p>\n<p>Il Comando Carabinieri per la Tutela della Salute da oltre 60 anni \u00e8 impegnato nell\u2019attenta vigilanza del settore alimentare per il rispetto delle norme poste a tutela della salute dei cittadini. <strong>L\u2019intensa attivit\u00e0<\/strong> sviluppata dalla Specialit\u00e0 dell\u2019Arma, d\u2019intesa con il Ministero della Salute, ha consentito, <strong>nell\u2019ultimo anno<\/strong>, di <strong>sottrarre dalle tavole degli italiani oltre 8.000 tonnellate di alimenti irregolari di varia natura<\/strong> (prodotti ittici, lattiero-caseari, carne, prodotti da forno e cereali, bibite e bevande), a causa di ignota provenienza, pessime condizioni igienico-sanitarie, stoccaggio in ambienti non adeguati, presenza di evidenti segni di alterazione o con date di scadenza superate, per un <strong>valore complessivo di oltre 34 milioni di euro.<\/strong><\/p>\n<p>Nel complesso sono state eseguite <strong>circa 27 mila ispezioni<\/strong> nei confronti dell\u2019intera filiera agroalimentare (produzione, distribuzione e ristorazione), rilevando irregolarit\u00e0 in oltre 10mila strutture ispezionate (il 37%). Nel corso dei controlli sono state accertate <strong>16.118 violazioni alle normative nazionali e comunitarie<\/strong> che disciplinano l\u2019igiene e la sicurezza degli alimenti; <strong>arrestati 3 operatori del settore alimentare<\/strong> (2 veterinari addetti ai controlli della filiera delle carni e lattiero-casearia per corruzione ed abuso di ufficio, un titolare di un caseificio per furto di energia elettrica), <strong>segnalati 9.328 soggetti alle Autorit\u00e0 competenti<\/strong> (di cui 772 denunciati all\u2019Autorit\u00e0 Giudiziaria), elevate <strong>sanzioni<\/strong> amministrative per oltre <strong>126 milioni di euro<\/strong>. 798 le strutture (depositi, ristoranti, panifici, attivit\u00e0 di produzione e vendita di alimenti vari, etc. per un valore complessivo di oltre 500 milioni di euro) chiuse per gravi irregolarit\u00e0 igienico-sanitarie ed autorizzative.<\/p>\n<h4><strong>Nas: le attivit\u00e0 delle ultime settimane<\/strong><\/h4>\n<p>Il Comando Carabinieri per la Tutela della Salute, ha eseguito una campagna di controllo mirata al contrasto delle forme illecite di commercializzazione di prodotti etnici importati e distribuiti su ampie aree del territorio nazionale, spesso caratterizzati dall\u2019assenza dei requisiti merceologici ed igienico-sanitari. Le <strong>verifiche<\/strong>, effettuate presso grossisti e distributori di <strong>alimenti etnici<\/strong> sono state volte ad accertare le condizioni igienico-sanitarie e strutturali degli ambienti, l\u2019attuazione delle procedure di sicurezza alimentare e tracciabilit\u00e0, nonch\u00e9 la posizione contrattuale delle maestranze ed il possesso di un\u2019adeguata formazione professionale.<\/p>\n<p>In tale specifico settore i <strong>Carabinieri NAS<\/strong> hanno <strong>effettuato circa 700 ispezioni<\/strong> che hanno determinato l\u2019accertamento di irregolarit\u00e0 in <strong>329 strutture<\/strong> (pari al 50% circa degli obiettivi controllati), a seguito delle quali sono state segnalate alla Autorit\u00e0 Giudiziaria e Sanitaria oltre 300 operatori di settore e contestate <strong>540 sanzioni amministrative<\/strong>, per un <strong>valore complessivo di oltre 500 mila euro.<\/strong><\/p>\n<p>Sono stati rinvenuti <strong>alimenti<\/strong> con la <strong>data di scadenza superata<\/strong>, artatamente cancellata e successivamente modificata in modo da procrastinarne la validit\u00e0. Scoperte, altres\u00ec 25 tonnellate di carni in pessimo stato di conservazione e in presenza di escrementi di roditori, nonch\u00e9 altri prodotti di origine extra comunitaria completamente ricoperti da liquido congelato, percolato dal soffitto a causa di malfunzionamento dell\u2019impianto di refrigerazione.<\/p>\n<p>Nel complesso, sono state sequestrate 200 tonnellate di prodotti alimentari (prodotti ittici, carnei, vegetali etc.) poich\u00e9 non idonei al consumo in quanto privi di tracciabilit\u00e0, in cattivo stato di conservazione e o detenuti in locali interessati carenze igieniche e\/o con etichettatura irregolare, per un valore <strong>commerciale di circa 4 milioni di euro<\/strong>. Nel corso delle attivit\u00e0 \u00e8 stato constatato <strong>l\u2019uso di magazzini abusivi di stoccaggio dei prodotti<\/strong>, depositi in pessime condizioni igienico-sanitarie, ambienti mancanti dei minimi requisiti sanitari, strutturali e di sicurezza per i lavoratori, che hanno comportato l\u2019applicazione di provvedimenti di chiusura o sospensione dell\u2019attivit\u00e0 a carico di 15 imprese commerciali.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Oggi 7 giugno si celebra la \u201cGiornata mondiale della sicurezza alimentare\u201d, iniziativa internazionale istituita nel 2019 dall\u2019Organizzazione Mondiale della Sanit\u00e0 (OMS), dall\u2019Organizzazione delle Nazioni Unite per l\u2019alimentazione e l\u2019agricoltura (FAO) e CODEX Alimentarius e dal Ministero della Salute &#8211; Direzione Generale per l\u2019Igiene e la Sicurezza degli Alimenti e la Nutrizione (DGISAN). Il [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":203739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-203735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203735"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/203739"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}