{"id":20381,"date":"2013-03-28T16:46:22","date_gmt":"2013-03-28T15:46:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20381"},"modified":"2023-01-17T13:18:11","modified_gmt":"2023-01-17T12:18:11","slug":"7719-i-love-shopping-di-kinsella-sophie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7719-i-love-shopping-di-kinsella-sophie\/","title":{"rendered":"&#8220;I love shopping&#8221; di Kinsella Sophie"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>&#8220;Quel momento, quell&#8217;istante in cui le dita si chiudono attorno ai manici di un sacchetto lucido e ancora perfettamente liscio, e tutte le fantastiche cose nuove al suo interno diventano tue, a cosa si pu\u00f2 paragonare?<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: center;\"><strong> \u00e8 come riempirsi la bocca di pane tostato e imburrato dopo aver fatto la fame per giorni. \u00e8 come svegliarsi al mattino e rendersi conto che \u00e8 sabato. \u00e8 come i momenti migliori del sesso. Tutto il resto scompare dalla mente. \u00e9 un piacere puro, assoluto, totale.&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Becky \u00e8 una giornalista carina e determinata, con una irrefrenabile passione: lo shopping. Irrefrenabile al punto da diventare una mania, che la spinge a comprare tutto: abiti, casalinghi, dolciumi, un paio di scarpe al posto di un litro di latte. In un susseguirsi di situazioni paradossali ma per nulla improbabili, &#8220;I love shopping&#8221; propone sorta di vademecum delle piccole manie del nostro tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Quel momento, quell&#8217;istante in cui le dita si chiudono attorno ai manici di un sacchetto lucido e ancora perfettamente liscio, e tutte le fantastiche cose nuove al suo interno diventano tue, a cosa si pu\u00f2 paragonare?<\/p>\n","protected":false},"author":22,"featured_media":20382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,25],"tags":[],"class_list":["post-20381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20381"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20382"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}