{"id":204139,"date":"2023-06-12T22:40:20","date_gmt":"2023-06-12T20:40:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=204139"},"modified":"2023-06-12T22:43:58","modified_gmt":"2023-06-12T20:43:58","slug":"terremoto-a-dasa-attimi-paura-e-gente-in-strada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/terremoto-a-dasa-attimi-paura-e-gente-in-strada\/","title":{"rendered":"Terremoto a Das\u00e0, attimi paura e gente in strada"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Un terremoto di magnitudo <b>3.0<\/b> si \u00e8 verificato circa un&#8217;ora fa con epicentro nella zona di<b> Das\u00e0, comune in provincia di Vibo Valentia. Il sisma, registrato alle 20:42 dalla Sala Sismica dell\u2019Istituto nazionale di Geologia e Vulcanologia \u00a0di Roma a tre chilometri a nord ovest di Das\u00e0, \u00e8 avvenuto a 15 chilometri di profondit\u00e0.\u00a0<\/b>Attimi di paura e diverse persone che sis ono riversate in strada al momento della scossa.<\/p>\n<p>Il terremoto \u00e8 stato avvertito dististantamente nella maggior parte dei centri del Vibonese e in alcune aree del Reggino e del Catanzarese. Al momento comunque non si registrano danni a persone o cose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Un terremoto di magnitudo 3.0 si \u00e8 verificato circa un&#8217;ora fa con epicentro nella zona di Das\u00e0, comune in provincia di Vibo Valentia. Il sisma, registrato alle 20:42 dalla Sala Sismica dell\u2019Istituto nazionale di Geologia e Vulcanologia \u00a0di Roma a tre chilometri a nord ovest di Das\u00e0, \u00e8 avvenuto a 15 chilometri [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":194265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-204139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=204139"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/194265"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=204139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=204139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=204139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}