{"id":204316,"date":"2023-06-14T19:33:40","date_gmt":"2023-06-14T17:33:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=204316"},"modified":"2023-06-14T19:33:40","modified_gmt":"2023-06-14T17:33:40","slug":"trasportavano-cocaina-pura-blitz-nel-cosentino-arrestati-due-fratelli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/trasportavano-cocaina-pura-blitz-nel-cosentino-arrestati-due-fratelli\/","title":{"rendered":"Trasportavano cocaina pura, blitz nel Cosentino: arrestati due fratelli"},"content":{"rendered":"<p>CORIGLIANO-ROSSANO &#8211; <strong>Controlli antidroga mirati a Corigliano Rossano<\/strong> hanno portato all&#8217;arresto di due uomini da parte dei carabinieri. Si tratta di <strong>due fratelli coriglianesi residenti per\u00f2 a Sibari, che da tempo erano monitorati dalle forze dell&#8217;ordine per i loro movimenti &#8216;sospetti&#8217;.<\/strong><\/p>\n<p>Fermati dall&#8217;Arma, i due hanno manifestato un comportamento sospetto. Di conseguenza, i militari hanno deciso di approfondire l\u2019indagine attraverso una perquisizione veicolare e personale. All&#8217;interno dell&#8217;auto sulla quale viaggiavano sono stati rinvenuti <strong>due pacchetti contenenti stupefacente, ben 215 grammi di cocaina pura <\/strong>che tagliata sarebbe poi finita sulle piazze di spaccio di Corigliano-Rossano.<\/p>\n<p>I soggetti arrestati sono poi stati trasferiti nel carcere di Castrovillari, a disposizione di quella Procura della Repubblica, che ha chiesto la convalida dei provvedimenti al GIP competente.<\/p>\n<p><strong>L\u2019azione di oggi \u00e8 parte integrante del piano di contrasto ai traffici di sostanze stupefacenti,<\/strong>\u00a0che tendono ad aumentare in questa stagione a causa dell\u2019afflusso di persone sulle spiagge della costa jonica.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO-ROSSANO &#8211; Controlli antidroga mirati a Corigliano Rossano hanno portato all&#8217;arresto di due uomini da parte dei carabinieri. Si tratta di due fratelli coriglianesi residenti per\u00f2 a Sibari, che da tempo erano monitorati dalle forze dell&#8217;ordine per i loro movimenti &#8216;sospetti&#8217;. Fermati dall&#8217;Arma, i due hanno manifestato un comportamento sospetto. Di conseguenza, i militari hanno [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":110993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-204316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=204316"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110993"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=204316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=204316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=204316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}