{"id":204552,"date":"2023-06-18T18:30:54","date_gmt":"2023-06-18T16:30:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=204552"},"modified":"2023-06-18T17:43:32","modified_gmt":"2023-06-18T15:43:32","slug":"a-bocchigliero-in-arrivo-lambulatorio-di-telemedicina-e-la-pista-per-lelisoccorso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-bocchigliero-in-arrivo-lambulatorio-di-telemedicina-e-la-pista-per-lelisoccorso\/","title":{"rendered":"\u00abA Bocchigliero in arrivo l&#8217;ambulatorio di telemedicina e la pista per l&#8217;elisoccorso\u00bb"},"content":{"rendered":"<p>BOCCHIGLIERO (CS) &#8211; &#8220;Oggi stiamo mandando <strong>un segnale importante e lo stiamo facendo in modo bellissimo e sano, camminando per coinvolgere pi\u00f9 donne possibile verso la prevenzione<\/strong>&#8221; \u00e8 quanto afferma l&#8217;On <strong>Pasqualina Straface Presidente della Terza Commissione Sanit\u00e0 regionale<\/strong> che nella mattinata odierna ha partecipato insieme a tante donne alla Prima edizione della &#8220;Passeggiata in rosa per la prevenzione&#8221; organizzata nel Comune di Bocchigliero dalla<br \/>\nPro loco e l&#8217;Associazione OncoMed di Cosenza.<\/p>\n<p>&#8220;La prevenzione \u00e8 la pi\u00f9 grande delle armi che abbiamo per lottare contro le malattie ed essere qui<strong>, tra tante donne per parlarne ed agire oggi \u00e8 fondamentale.<\/strong> Aggiungiamo un altro tassello al disegno pi\u00f9 grande che si sta delineando, infatti \u00e8 attraverso<strong> il lavoro di squadra e sinergico che vede la Regione Calabria in prima linea nel sostenere le Asp nelle campagne sulle prevenzione che stanno mettendo in moto, che si raggiunger\u00e0 un sempre maggior numero di persone<\/strong>.<\/p>\n<p>Ringrazio quindi la presidente della Proloco Maria Rosaria Rizzuti, il Dr Pietro Leonardo Perri, la Dr.ssa Mariagrazia Politano, la Dr.ssa Vittoria Paletta, la Dr.ssa Anna Pugliese, la dott.ssa\u2028Carmela Sciarrotta, l&#8217;ostetrica Vittoria Valente, \u2028Sonia Butera, il Dr. Iacovino e Maria Jos\u00e8 Caligiuri di &#8220;Azzurro Donne&#8221; che sono intervenuti con me per parlare di prevenzione ma anche delle prossime novit\u00e0 che riguarderanno la sanit\u00e0 nel comune di Bocchigliero. <strong>I Comuni che si trovano geograficamente nell&#8217; entroterra e che sono pi\u00f9 piccoli&#8221; continua la presidente della Terza Commissione Sanit\u00e0 &#8220;hanno subito in passato molti, troppi tagli e privazioni<\/strong> sanitarie ma oggi <strong>le cose stanno cambiando<\/strong> perch\u00e9 nei prossimi mesi, Bocchigliero vedr\u00e0 una serie di servizi a favore della cittadinanza. <strong>Il potenziamento della rete territoriale vedr\u00e0 l&#8217;attivazione specialistica ambulatoriale di geriatria, cardiologia e diabetologia, verr\u00e0 poi attivato il Cup e l&#8217;assistenza agli utenti, due grandissime novit\u00e0 r<\/strong>iguardano invece l&#8217;apertura del primo ambulatorio di telemedicina della nostra Asp, attraverso il quale saranno le informazioni a muoversi e non i pazienti, andando anche a colmare quel gap derivante dalla distanza dai presidi sanitari; si potranno dunque&#8221; sottolinea<strong> l&#8217;On Straface &#8220;visitare e televisitare i pazienti, eseguire prestazioni come elettrocardiogrammi ed ecografie<\/strong> che verranno trasmessi e visionati dai medici dello Spoke di Corigliano-Rossano e a gestire i device saranno operatori sanitari formati proprio nella gestione di dati e programmi.<\/p>\n<p>L&#8217;altra importante novit\u00e0,<strong> \u00e8 che verr\u00e0 realizzata la pista per l&#8217;elisoccorso e questo permetter\u00e0 non solo di accorciare le distanze geografiche ma sar\u00e0 fondamentale per diminuire drasticamente le tempistiche di salvataggio. <\/strong>Queste sono solo alcune delle ultime novit\u00e0 che riguardano il riordino della nostra sanit\u00e0 sotto la guida del Presidente Roberto Occhiuto, che passo dopo passo ci condurr\u00e0 verso un sistema sanitario pi\u00f9 pragmatico, efficiente e su campagne di prevenzione fondamentali per la popolazione.<\/p>\n<p>Come Presidente della Terza Commissione Sanit\u00e0 e ancora prima come donna&#8221; conclude l&#8217;On Straface &#8220;credo che la prevenzione sia fondamentale per proteggerci e bloccare in fase iniziale le patologie che potrebbero colpirci.<br \/>\nNoi donne tendiamo a trascurarci spesso tra le mille cose che abbiamo da fare lavoro, famiglia, impegni multipli ma dobbiamo credere nella prevenzione e decidere di prenderci cura di noi stesse&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOCCHIGLIERO (CS) &#8211; &#8220;Oggi stiamo mandando un segnale importante e lo stiamo facendo in modo bellissimo e sano, camminando per coinvolgere pi\u00f9 donne possibile verso la prevenzione&#8221; \u00e8 quanto afferma l&#8217;On Pasqualina Straface Presidente della Terza Commissione Sanit\u00e0 regionale che nella mattinata odierna ha partecipato insieme a tante donne alla Prima edizione della &#8220;Passeggiata in [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":204553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-204552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=204552"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204553"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=204552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=204552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=204552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}