{"id":204639,"date":"2023-06-19T16:00:20","date_gmt":"2023-06-19T14:00:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=204639"},"modified":"2023-06-20T11:57:22","modified_gmt":"2023-06-20T09:57:22","slug":"il-2022-e-stato-lanno-piu-caldo-della-storia-in-italia-e-potrebbe-essere-battuto-dal-2023","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/il-2022-e-stato-lanno-piu-caldo-della-storia-in-italia-e-potrebbe-essere-battuto-dal-2023\/","title":{"rendered":"Il 2022 \u00e8 stato l&#8217;anno pi\u00f9 caldo della storia in Italia. E potrebbe essere battuto dal 2023"},"content":{"rendered":"<p>COSENZA &#8211;<strong> Il 2022 \u00e8 stato l&#8217;anno pi\u00f9 caldo mai registrato in Italia<\/strong> da quando ci sono rilevazioni scientifiche, dalla seconda met\u00e0 dell&#8217;Ottocento. Lo rivela il rapporto <strong>&#8220;Stato del Clima in Europa 2022<\/strong>&#8220;, preparato congiuntamente dall&#8217;Organizzazione meteorologica mondiale (Wmo) e dal servizio Ue di osservazione della Terra, <a href=\"https:\/\/climate.copernicus.eu\/\" rel=\"noopener\">Copernicus<\/a>.<\/p>\n<h3>Temperature record anche in tutta Europa<\/h3>\n<p>Il 2022 \u00e8 stato l&#8217;anno pi\u00f9 caldo mai registrato anche in Belgio, Francia, Germania, Irlanda, Lussemburgo, Portogallo, Spagna, Svizzera e Regno Unito. <strong>Per l&#8217;intera Europa, l&#8217;anno passato \u00e8 stato il 2\/o pi\u00f9 caldo della storia<\/strong> e l&#8217;estate 2022 \u00e8 stata la pi\u00f9 calda in assoluto mai registrata nel continente. Segnali poco incoraggianti arrivano anche nelle previsioni per il 2023 che potrebbe rivelarsi uno degli anni pi\u00f9 caldi (se non il pi\u00f9 caldo) dall&#8217;inizio delle misurazioni moderne.<\/p>\n<h3>Previsioni: 2023 ancora pi\u00f9 caldo<\/h3>\n<p>Le previsioni indicano quindi un&#8217;elevata probabilit\u00e0 che in questa estate 2023 e poi in autunno e in inverno si superi nuovamente, e ripetutamente, il grado e mezzo al di sopra delle temperature pre-industriali.<\/p>\n<p>In Europa dove, nel 2022, <strong>la temperatura media \u00e8 stata di 2,3 gradi sopra i livelli pre-industriali (1850 &#8211; 1900). Il continente dal 1980 si \u00e8 riscaldato il doppio della media globale<\/strong>. &#8220;Il cambiamento climatico sta imponendo un notevole sacrificio a livello umano, economico e ambientale. <strong>L&#8217;anno 2022 \u00e8 stato caratterizzato da condizioni di caldo estremo, siccit\u00e0 e incendi<\/strong>. Le temperature della superficie del mare in tutta Europa hanno raggiunto nuovi massimi, accompagnati da ondate di calore marino. Inoltre, lo scioglimento dei ghiacciai \u00e8 stato senza precedenti&#8221;.<\/p>\n<p>Secondo il database delle situazioni di emergenza (Em-Dat), i rischi meteorologici, idrologici e climatici che si sono verificati in Europa nel 2022 hanno colpito direttamente 156mila persone e provocato 16.365 morti, quasi esclusivamente a causa delle ondate di calore. Dal 1980, i disastri meteorologici (ondate di calore, inondazioni, ecc.) hanno provocato la morte di 195 mila persone, ha reso noto l&#8217;Agenzia europea dell&#8217;ambiente (Aea).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il 2022 \u00e8 stato l&#8217;anno pi\u00f9 caldo mai registrato in Italia da quando ci sono rilevazioni scientifiche, dalla seconda met\u00e0 dell&#8217;Ottocento. Lo rivela il rapporto &#8220;Stato del Clima in Europa 2022&#8220;, preparato congiuntamente dall&#8217;Organizzazione meteorologica mondiale (Wmo) e dal servizio Ue di osservazione della Terra, Copernicus. Temperature record anche in tutta Europa Il [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":204641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-204639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=204639"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204641"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=204639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=204639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=204639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}