{"id":204950,"date":"2023-06-25T08:00:57","date_gmt":"2023-06-25T06:00:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=204950"},"modified":"2023-06-24T08:47:55","modified_gmt":"2023-06-24T06:47:55","slug":"il-pilota-cosentino-quintieri-stupisce-ancora-prossimo-test-a-cremona-nella-formula-4","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/il-pilota-cosentino-quintieri-stupisce-ancora-prossimo-test-a-cremona-nella-formula-4\/","title":{"rendered":"Il pilota cosentino Quintieri stupisce ancora, prossimo test a Cremona nella Formula 4"},"content":{"rendered":"<p>COSENZA &#8211; Il sesto posto in gara, all&#8217;esordio. Continua a stupire il 15enne pilota cosentino di kart, Ermanno Quintieri. Il giovanissimo corridore \u00e8 reduce dal <strong>Campionato Italiano Aci Karting<\/strong> sul circuito internazionale di La Conca, in provincia di Lecce. Una gara resa difficile dalle condizioni meteo avverse: la forte pioggia ha impegnato i piloti e reso la pista ai limiti della praticabilit\u00e0.<\/p>\n<p>Quintieri era all&#8217;esordio assoluto nella categoria \u201c<strong>P6 KZ2 under 18\u201d.<\/strong> Il pilota cosentino, il pi\u00f9 giovane in pista, ha ottenuto un sesto posto che gli ha permesso di raccogliere applausi e consensi degli addetti ai lavori.<\/p>\n<p>Un percorso continuo di crescita per il pilota di kart che il prossimo marted\u00ec 27 giugno <strong>sosterr\u00e0 un test a Cremona nella Formula<\/strong> <strong>4:<\/strong> la categoria successiva al karting. In buona sostanza, il primo vero assaggio del mondo delle corse automobilistiche, un passaggio obbligato e obbligatorio per continuare a sognare l&#8217;esordio in Formula 1, il vero obiettivo di Ermanno Quintieri.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-204951 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02.jpg\" alt=\"Ermanno Quintieri pilota in pista 02\" width=\"543\" height=\"336\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/Ermanno-Quintieri-pilota-in-pista-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il sesto posto in gara, all&#8217;esordio. Continua a stupire il 15enne pilota cosentino di kart, Ermanno Quintieri. Il giovanissimo corridore \u00e8 reduce dal Campionato Italiano Aci Karting sul circuito internazionale di La Conca, in provincia di Lecce. Una gara resa difficile dalle condizioni meteo avverse: la forte pioggia ha impegnato i piloti e [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":204952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-204950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=204950"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/204950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204952"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=204950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=204950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=204950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}