{"id":20549,"date":"2013-04-03T06:10:32","date_gmt":"2013-04-03T04:10:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20549"},"modified":"2023-01-17T13:18:20","modified_gmt":"2023-01-17T12:18:20","slug":"7806-detenzione-illegale-di-arma-e-ricettazione-un-arresto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7806-detenzione-illegale-di-arma-e-ricettazione-un-arresto\/","title":{"rendered":"Detenzione illegale di arma e ricettazione, un arresto"},"content":{"rendered":"<p><strong>CATANZARO<\/strong> &#8211; Arrestato Antonio Marrazzo, 37 anni, dai Carabinieri della stazione di Sambiase, con l&#8217;accusa di detenzione illegale di arma e ricettazione. Durante un servizio<\/p>\n<p>  <!--more-->  <\/p>\n<p>preventivo e di controllo del territorio, nel corso di una perquisizione personale e domiciliare effettuata dai militari a carico dell&#8217;uomoi, e&#8217; stata rinvenuta una pistola 7,65 modificata e oggetto di furto. L&#8217;arma era nascosta in una botola del sottotetto dell&#8217;abitazione dei Marrazzo, all&#8217;interno di una valigetta insieme con 60 di proiettili calibro 7,65, due caricatori pieni e un silenziatore metallico di colore nero a manifattura artigianale. Durante la perquisizione e&#8217; stata anche sequestrata una carabina con relativo munizionamento calibro 22 non denunciato. Marrazzo e&#8217; stato dichiarato in stato di arresto e tradotto nella locale casa circondariale cosi&#8217; come disposto dall&#8217;autorita&#8217; giudiziaria, mentre le armi sono state inviate ai laboratori del RIS di Messina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Arrestato Antonio Marrazzo, 37 anni, dai Carabinieri della stazione di Sambiase, con l&#8217;accusa di detenzione illegale di arma e ricettazione. Durante un servizio<\/p>\n","protected":false},"author":22,"featured_media":20550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-20549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20549"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20550"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}