{"id":20607,"date":"2013-04-03T15:08:09","date_gmt":"2013-04-03T13:08:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20607"},"modified":"2023-01-17T13:18:23","modified_gmt":"2023-01-17T12:18:23","slug":"7836-rossella-vitaro-eccellenza-universitaria-di-firenze","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7836-rossella-vitaro-eccellenza-universitaria-di-firenze\/","title":{"rendered":"Rossella Vitaro, eccellenza universitaria di Firenze"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Complimenti Rossella. <strong>Tra le eccellenze studentesche, premiate dall&#8217;Universit\u00e0 di Firenze, per la rapidit\u00e0 con cui hanno<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong> concluso il loro percorso di studi, c&#8217;\u00e8 anche la cosentina Rosella Vitaro, che, al pari di altri suoi undici compagni di viaggio, ha staccato in largo anticipo il biglietto per la laurea. Rossella, 22 anni, \u00e8 stata premiata per essere stata la prima e pi\u00f9 brava ad essersi laureata in Psicologia. Caparbia, decisa, desiderosa di conoscenza, assetata di cultura e affamata di sapere, la 22enne, ha accantonato l&#8217;idea di ritornare in Calabria, coltivando l&#8217;idea di non diventare l&#8217;ennesimo &#8220;cervello&#8221; emigrante all&#8217;estero. &#8220;Ho fatto un patto con me stessa, mi sono data un tempo massimo entro cui trovare un lavoro gratificante&#8221;. Lei ha scelto la strada dell&#8217;ascolto e quella dello studio e dell&#8217;interpretazione degli altri, ma sa bene che &#8220;essere bravi studenti, non significa, per come \u00e8 messo il Paese, nella garanzia di avere la certezza di un lavoro. Ma sono ottimista e devo dire anche coraggiosa&#8221;.<\/strong> Rossella, come dicevamo, \u00e8 stata premiata insieme agli altri &#8220;magnifici undici&#8221; che si sono laureati con il massimo dei voti nel minor tempo possibile.<strong> In un&#8217;apposita cerimonia, organizzata nei minimi dettagli da&#8221;Universit\u00e0 fiorentina, il rettore Alberto Tesi, nella splendida cornice del&#8217;aula Magna in piazza San Marco, ha premiato anche Giuseppe Spinelli, anche lui 22enne, laureato in Lettere e Filosofia; Giulia Carbonari (22), diventata dottoressa in Scienze Politiche in Relazione Internazionali; Arianna De Matteis, di anni ne ha 25 ed \u00e8 foggiana, si \u00e8 laureata in Medicina e Chirurgia; Matteo Galanti, fiorentino doc, di anni ne ha 22, ha finito con la velocit\u00e0 di un razzo il suo percorso in Ingegneria. La pi\u00f9 giovane \u00e8 Giulia Paternostro. Lei di anni ne ha 21 e ha conseguito il titolo in Scienze della Formazione. Francesca Mazza, 24enne, figlia di medici, ha scelto di non seguire le orme dei genitori, scegliendo la laurea in Giurisprudenza,. Valentina Noccioli, fiorentina di 24 anni, s&#8217;\u00e8 laureata in Farmacia. Gli ultimi due premiati, ma solo per ordine di inserimento in lista, sono stati Marta Landi in Agraria e Andrea Guarino (Architettura). <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Complimenti Rossella. Tra le eccellenze studentesche, premiate dall&#8217;Universit\u00e0 di Firenze, per la rapidit\u00e0 con cui hanno<\/p>\n","protected":false},"author":22,"featured_media":20608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-20607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20607"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20608"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}