{"id":206144,"date":"2023-07-07T19:00:34","date_gmt":"2023-07-07T17:00:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=206144"},"modified":"2023-07-07T20:16:33","modified_gmt":"2023-07-07T18:16:33","slug":"concorso-agenzia-delle-entrate-4-500-assunzioni-di-funzionari-e-dirigenti-2023-2024","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/concorso-agenzia-delle-entrate-4-500-assunzioni-di-funzionari-e-dirigenti-2023-2024\/","title":{"rendered":"Concorso Agenzia delle Entrate: 4.500 assunzioni di funzionari e dirigenti 2023\/2024"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Concorso Agenzia delle Entrate<\/strong>: prevista l&#8217;<strong>assunzione di 4.500 funzionari e dirigenti<\/strong>. A darne notizia la stessa Agenzia delle Entrate che ha in programma di pubblicare, <strong>nell\u2019anno 2023 e nel primo semestre 2024<\/strong>, i <a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/PROGRAMMAZIONE-ASSUNZIONE-LUGLIO-2023-Agenzia-delle-Entrate.pdf\">bandi di concorso<\/a> per il reclutamento del personale rivolto a <strong>esperti in materia fiscale e catastale, ingegneri per logistica e contratti, informatici ed esperti in risorse umane<\/strong>.\u00a0&#8220;Sono altres\u00ec delineati i profili ricercati al solo fine di permettere ai potenziali candidati di programmare lo studio e la preparazione per affrontare le selezioni concorsuali&#8221;. Tutte le info si trovano sul sito dell&#8217;<a href=\"https:\/\/www.agenziaentrate.gov.it\/portale\/web\/guest\/agenzia\/amministrazione-trasparente\/bandi-di-concorso\" rel=\"noopener\">Agenzia delle Entrate<\/a> oppure scarica e leggi qui il <i class=\"fa fa fa-file-pdf-o\" aria-hidden=\"true\"><\/i>\u00a0<a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/PROGRAMMAZIONE-ASSUNZIONE-LUGLIO-2023-Agenzia-delle-Entrate.pdf\">Programma di pubblicazione di bandi di concorso per gli anni 2023 e 2024<\/a><\/p>\n<h3><strong>Concorso Agenzia delle entrate: tutti i profili\u00a0<\/strong><\/h3>\n<p><strong>1- Concorso Funzionari per attivit\u00e0 tributaria<\/strong><\/p>\n<p>Attivit\u00e0 in materia fiscale, assistenza e consulenza all\u2019utenza su adempimenti contabili e fiscali, attivit\u00e0 di gestione ed erogazione dei servizi fiscali e di analisi ed elaborazione della modulistica fiscale, attivit\u00e0 di analisi e ricerca dei fenomeni illeciti, attivit\u00e0 esterne di verifica e accesso mirato, attivit\u00e0 di controllo sostanziale e di accertamento fiscale, contenzioso tributario e riscossione.<\/p>\n<p><strong>2 -Concorso Funzionari per servizi di pubblicit\u00e0 immobiliare<\/strong><\/p>\n<p>Servizi di pubblicit\u00e0 immobiliare, assistenza e consulenza agli utenti, attivit\u00e0 di aggiornamento e conservazione delle banche dati di pubblicit\u00e0 immobiliare, procedimenti di volontaria giurisdizione, attivit\u00e0 di monitoraggio in caso di rifiuto o riserva dei conservatori.<\/p>\n<h2><span style=\"color: #ff0000;\"><strong>SECONDO SEMESTRE 2023<\/strong><\/span><\/h2>\n<p><strong>3- Concorso Funzionari per processi di logistica e approvvigionamenti:<\/strong><\/p>\n<p>Attivit\u00e0 di pianificazione degli approvvigionamenti di beni, servizi e lavori, rilevazione del fabbisogno, predisposizione delle gare e gestione dei contratti, gestione degli immobili e dei programmi di manutenzione, rendicontazione dei lavori, attivit\u00e0 di tutela e sicurezza dei lavoratori, progettazione e presidio dell&#8217;adeguamento degli immobili alla normativa.<\/p>\n<p><strong>4 &#8211; Concorso Funzionari analista dati, infrastrutture e sicurezza informatica:<\/strong><\/p>\n<p>Attivit\u00e0 connesse all\u2019esercizio, sviluppo e monitoraggio del sistema informatico, definizione dei piani di sviluppo tecnologico, supporto nell\u2019individuazione delle esigenze di automazione, analisi tecnologica, assistenza tecnica per la realizzazione delle procedure, attivit\u00e0 di sicurezza, analisi dei dati e cooperazione informatica, monitoraggio dei contratti ICT.<\/p>\n<h1><strong><span style=\"color: #ff0000;\">ANNO 2024<\/span><\/strong><\/h1>\n<p><strong>1 &#8211; Concorso Funzionari per attivit\u00e0 di selezione, valutazione, formazione e sviluppo delle risorse umane<\/strong><\/p>\n<p>Attivit\u00e0 di gestione delle risorse umane, attivit\u00e0 di rilevazione del fabbisogno formativo; selezione e sviluppo professionale, sistemi e processi di valutazione del personale.<\/p>\n<p><strong>2 &#8211; Concorso Funzionari tecnic<\/strong>i<\/p>\n<p>Attivit\u00e0 relative ai servizi catastali, cartografici, estimativi e dell\u2019osservatorio del mercato immobiliare.<\/p>\n<p>3)\u00a0 <strong>Concorso <\/strong><strong>\u00a0Dirigenti di seconda fascia da destinare prioritariamente agli uffici preposti alla gestione delle risorse umane e materiali dell\u2019Agenzia delle entrate<\/strong><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/PROGRAMMAZIONE-ASSUNZIONE-LUGLIO-2023-Agenzia-delle-Entrate.pdf\">Scarica il programma di pubblicazione dei bandi &#8211; Concorso Agenzie delle Entrate per gli anni 2023 e 2024<\/a><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Concorso Agenzia delle Entrate: prevista l&#8217;assunzione di 4.500 funzionari e dirigenti. A darne notizia la stessa Agenzia delle Entrate che ha in programma di pubblicare, nell\u2019anno 2023 e nel primo semestre 2024, i bandi di concorso per il reclutamento del personale rivolto a esperti in materia fiscale e catastale, ingegneri per logistica e [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":187308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-206144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=206144"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/187308"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=206144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=206144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=206144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}