{"id":206191,"date":"2023-07-08T17:14:33","date_gmt":"2023-07-08T15:14:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=206191"},"modified":"2023-07-08T17:14:33","modified_gmt":"2023-07-08T15:14:33","slug":"lite-sul-lungomare-finisce-a-coltellate-arrestato-il-presunto-autore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lite-sul-lungomare-finisce-a-coltellate-arrestato-il-presunto-autore\/","title":{"rendered":"Lite sul lungomare finisce a coltellate, arrestato il presunto autore"},"content":{"rendered":"<p>CROTONE &#8211; I carabinieri hanno arrestato un uomo per tentato omicidio, minacce e porto abusivo di armi o strumenti atti ad offendere. Secondo quanto ricostruito ieri, al culmine di una violenta lite scoppiata per futili motivi sul <strong>lungomare di Torre Melissa<\/strong>, avrebbe ferito con un coltello un&#8217;altra persona colpendola al fianco ed alla schiena. <strong>L&#8217;autore del gesto<\/strong> si \u00e8 poi dato alla fuga ma i carabinieri intervenuti prontamente, sono riusciti a raccogliere subito indizi sul conto dell&#8217;aggressore e a bloccarlo. Il <strong>ferito<\/strong>, trovato a terra ricoperto di sangue, in <strong>gravi condizioni<\/strong>, \u00e8 stato <strong>portato in ospedale.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; I carabinieri hanno arrestato un uomo per tentato omicidio, minacce e porto abusivo di armi o strumenti atti ad offendere. Secondo quanto ricostruito ieri, al culmine di una violenta lite scoppiata per futili motivi sul lungomare di Torre Melissa, avrebbe ferito con un coltello un&#8217;altra persona colpendola al fianco ed alla schiena. L&#8217;autore [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":194871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-206191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=206191"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/194871"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=206191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=206191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=206191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}