{"id":206201,"date":"2023-07-09T08:40:42","date_gmt":"2023-07-09T06:40:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=206201"},"modified":"2023-07-09T08:41:33","modified_gmt":"2023-07-09T06:41:33","slug":"migranti-in-calabria-gli-sbarchi-continuano-a-roccella-arrivate-48-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/migranti-in-calabria-gli-sbarchi-continuano-a-roccella-arrivate-48-persone\/","title":{"rendered":"Migranti: in Calabria gli sbarchi continuano, a Roccella arrivate 48 persone"},"content":{"rendered":"<p>ROCCELLA JONICA (RC) &#8211; Sono stati 48 i migranti arrivati ieri sera al porto di Roccella Ionica, nella Locride. L&#8217;ultimo sbarco, in ordine di tempo, si \u00e8 verificato ieri dopo l&#8217;ennesima operazione di soccorso in mare effettuata dalla Guardia Costiera di Roccella Ionica. Le 48 persone, tutte di nazionalit\u00e0 afghana e siriana, sono state intercettate al largo mentre viaggiavano a <strong>bordo di una barca a vela<\/strong> e portati nello scalo della Locride.<\/p>\n<p>Del gruppo fanno parte <strong>tre donne in stato di gravidanza e sei minori<\/strong>. Dopo lo sbarco i migranti sono stati temporaneamente ospitati, su disposizione della Prefettura di Reggio Calabria, nella tensostruttura allestita nell&#8217;area portuale, ormai al massimo della capienza. E sale a 28 il numero degli sbarchi dall&#8217;inizio dell&#8217;anno per un totale di circa 4mila arrivi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROCCELLA JONICA (RC) &#8211; Sono stati 48 i migranti arrivati ieri sera al porto di Roccella Ionica, nella Locride. L&#8217;ultimo sbarco, in ordine di tempo, si \u00e8 verificato ieri dopo l&#8217;ennesima operazione di soccorso in mare effettuata dalla Guardia Costiera di Roccella Ionica. Le 48 persone, tutte di nazionalit\u00e0 afghana e siriana, sono state intercettate [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":204336,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-206201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=206201"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204336"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=206201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=206201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=206201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}