{"id":206645,"date":"2023-07-17T07:00:30","date_gmt":"2023-07-17T05:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=206645"},"modified":"2023-07-17T07:17:11","modified_gmt":"2023-07-17T05:17:11","slug":"loms-dichiara-laspartame-possibilmente-cancerogeno-qual-e-la-dose-da-non-superare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/loms-dichiara-laspartame-possibilmente-cancerogeno-qual-e-la-dose-da-non-superare\/","title":{"rendered":"L&#8217;Oms dichiara l&#8217;aspartame possibilmente cancerogeno: qual \u00e8 la dose da non superare"},"content":{"rendered":"<p>ROMA &#8211; L&#8217;<strong>aspartame \u00e8 &#8220;possibilmente cancerogeno per l&#8217;uomo&#8221;<\/strong>. L&#8217;Oms, dopo settimane di indiscrezioni,<strong> ha ufficialmente classificato il dolcificante artificiale comunemente usato nelle bevande analcoliche<\/strong> come potenzialmente rischioso. Il livello di assunzione giornaliera considerato accettabile \u00e8 rimasto invariato.<\/p>\n<h3><strong>La decisione<\/strong><\/h3>\n<p>L&#8217;Iarc, Agenzia internazionale per la ricerca sul cancro dell&#8217;Oms, ha effettuato<strong> la sua prima valutazione della cancerogenicit\u00e0 dell&#8217;aspartame durante un incontro a Lione, in Francia, dal 6 al 13 giugno<\/strong>. &#8220;Il gruppo di lavoro ha classificato l&#8217;aspartame come possibilmente cancerogeno per l&#8217;uomo&#8221;, ha detto l&#8217;Oms che ha inserito l&#8217;aspartame nella categoria Gruppo 2B, sulla base di test che riguardavano specificamente il carcinoma epatocellulare, un tipo di cancro al fegato. \u00c8 bene ricordare che lo Iarc suddivide le sostanze in quattro categorie: <strong>cancerogene per l\u2019uomo (gruppo 1), probabili cancerogeni (gruppo 2A), possibili cancerogeni (gruppo 2B), non classificabili come cancerogeni (gruppo 3). Altri test sono stati effettuati su animali da laboratorio<\/strong>. La categoria Gruppo 2B contiene anche l&#8217;estratto di aloe vera e l&#8217;acido caffeico presenti nel t\u00e8 e nel caff\u00e8, ha affermato Paul Pharoah, professore di epidemiologia del cancro presso il Cedars-Sinai Medical Center di Los Angeles, aggiungendo che<strong> &#8220;il &#8216;pubblico&#8217; in generale non dovrebbe essere preoccupato per il rischio di cancro associato a una sostanza chimica classificata come gruppo 2B<\/strong>&#8220;.<\/p>\n<h3><strong>La dose giornaliera<\/strong><\/h3>\n<p>Un secondo gruppo, il Jecfa, il comitato congiunto di esperti sugli additivi alimentari formato dall&#8217;Oms e da un&#8217;altra agenzia delle Nazioni Unite, l&#8217;Organizzazione per l&#8217;alimentazione e l&#8217;agricoltura, si \u00e8 riunito a Ginevra dal 27 giugno al 6 luglio per valutare la rischi associati all&#8217;aspartame e ha concluso che non c&#8217;\u00e8 alcun motivo per modificare la dose giornaliera accettabile stabilita nel 1981,<strong> ovvero da zero a 40 milligrammi di aspartame per chilogrammo di peso corporeo.<\/strong> Con una lattina di bibita analcolica senza zucchero <strong>contenente 200 o 300 mg di dolcificante aspartame, un adulto del peso di 70 chili dovrebbe quindi consumare pi\u00f9 di 9-14 lattine al giorno<\/strong> per superare il limite, supponendo che non venga assunto ulteriore aspartame da altre fonti.<\/p>\n<h3><strong>&#8220;Stiamo solo consigliando un po&#8217; di moderazione&#8221;<\/strong><\/h3>\n<p>&#8220;Non stiamo consigliando alle aziende di ritirare i prodotti, <strong>n\u00e9 stiamo consigliando ai consumatori di smettere del tutto di consumarli<\/strong>&#8220;. Lo ha affermato Francesco Branca, direttore della nutrizione e della sicurezza alimentare dell&#8217;Organizzazione mondiale della sanit\u00e0, aggiungendo che &#8220;stiamo solo consigliando un po&#8217; di moderazione&#8221;.<\/p>\n<p>Mary Schubauer-Berigan della Iarc ha affermato che<strong> le prove riferite al carcinoma epatocellulare provengono da tre studi, condotti negli Stati Uniti e in 10 Paesi europei.<\/strong> &#8220;Questi sono gli unici studi epidemiologici che hanno esaminato il cancro al fegato&#8221;, ha detto ai giornalisti. Branca ha aggiunto: &#8220;Abbiamo, in un certo senso, lanciato un segnale, indicando che dobbiamo chiarire molto meglio la situazione&#8221;, ma non \u00e8 nemmeno &#8220;qualcosa che possiamo liquidare.<strong> Il problema \u00e8 per i grandi consumatori&#8221;, ha detto il direttore della nutrizione e della sicurezza alimentare<\/strong> specificando che &#8220;chi beve una bibita ogni tanto non dovrebbe preoccuparsi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; L&#8217;aspartame \u00e8 &#8220;possibilmente cancerogeno per l&#8217;uomo&#8221;. L&#8217;Oms, dopo settimane di indiscrezioni, ha ufficialmente classificato il dolcificante artificiale comunemente usato nelle bevande analcoliche come potenzialmente rischioso. Il livello di assunzione giornaliera considerato accettabile \u00e8 rimasto invariato. La decisione L&#8217;Iarc, Agenzia internazionale per la ricerca sul cancro dell&#8217;Oms, ha effettuato la sua prima valutazione della [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":206647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-206645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=206645"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/206645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/206647"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=206645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=206645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=206645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}