{"id":20675,"date":"2013-04-04T18:13:10","date_gmt":"2013-04-04T16:13:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20675"},"modified":"2023-01-17T13:18:28","modified_gmt":"2023-01-17T12:18:28","slug":"7870-fate-largo-e-arrivata-la-primavera","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7870-fate-largo-e-arrivata-la-primavera\/","title":{"rendered":"Fate largo, \u00e8 arrivata la primavera"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Vestiti di leggerezza. <strong>Dopo essersi, seppur con fatica e vigore, liberata dalla stretta prigionia del &#8220;generale&#8221; inverno e delle<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong> sue truppe temporalesche, la primavera, come una principessa, si \u00e8 riappropriata, anche in in ritardo, del regno del suo tempo. E&#8217; questa la pi\u00f9 bella espressione che la collega Katia Grosso (nuova e brava risorsa della nostra redazione, ndr) ha utilizzato per raccontare il potere della primavera, quella che &#8220;accende&#8221; il sorriso sui volti della gente, quella che irradia di felicit\u00e0 gli occhi delle persone, quella che invita con positivit\u00e0 a pensare alla bella stagione. Gi\u00e0 la bella stagione: i pomeriggi soleggiati, l&#8217;aria profumata di fiori, i corpi svestiti dalle &#8220;armature&#8221; dell&#8217;inverno e la voglia di mare, vacanze e ozio. Per capire meglio l&#8217;aria di primavera e lasciarsi contagiare dalla sua energica essenza, Katia Grosso ha deciso, di raccontare, come solo un articolo a volte sa fare, quest&#8217;atmosfera. Lei che, vivendo di mare, sole e aria pulita, il soffio di primavera la sente arrivare prima, mentre sbatte sugli scogli, ci prende per mano e ci accompagna alla scoperta dei simboli di questa nuova ventata di rinascita primaverile.<\/strong>&nbsp;Lo fa, innanzitutto, raccontandoci di Grazia, un&#8217;erborista che ha visto gli effetti della primavera, entrare nel suo negozio. Grazia, grandi occhi azzurri, color cielo, lunghi capelli castani e viso radioso, \u00e8 l&#8217;emblema della primavera, quella che si prepara all&#8217;estate, quella che tiene alla linea, quella che cerca l&#8217;elisir naturale per drenare le tossine accumulate durante l&#8217;inverno. <strong>&#8220;Sono in tante le donne, di diverse fasce d&#8217;et\u00e0, che sono pronte a prepararsi per l&#8217;estate. La primavera mette addosso un&#8217;allegria particolare, una carica emotiva forte, un&#8217;energia positiva che \u00e8 contagiosa. Dopo essere stati per tanto tempo, immobilizzate in ingombranti pullover, in grandi cappotti e sciarpe ora \u00e8 il momento di respirare quest&#8217;aria che fa bene ai pensieri, fa bene alla pelle, fa bene all&#8217;umore&#8221;.<\/strong> Nel corso della chiacchierata con Katia, l&#8217;erborista indica i prodotti che vanno per la maggiore. &#8220;Nulla di nuovo, sono quelli di sempre, con qualche novit\u00e0, ma generalmente la clientela, fidelizzata su alcuni prodotti, difficilmente cambia&#8221;. Grazia, fa osservare che, da qualche anno, la tendenza \u00e8 aumentata anche fra gli uomini.<strong> &#8220;Devo dire che sono diversi i clienti che entrano. Quello che mi colpisce, spesso, \u00e8 la loro sicurezza nell&#8217;acquisto: creme lenitive, inguenti riposanti e anche ritocchi contro le rughe. Ci sono anche quelli che vanno oltre, eccedendo, ma forse quello fa parte di un misto tra edonismo e narcisismo, forse anche per compensare delle eventuali insicurezze emotive&#8221;.<\/strong> Parlando di corpi, un passaggio in palestra \u00e8 obbligatorio. <strong>Claudio e Francesca, fidanzati da sette anni, gestiscono una palestra in centro. Anche loro hanno visto un leggero aumento delle presenze da qualche giorno. &#8220;Si, sono state tante le donne, le ragazze che si sono venute ad informare, su costi, orari e variet\u00e0 di allenamenti. I pi\u00f9 gettonati sono il zumba fitness, l&#8217;intramontabile aerobica, gli esercizi a corpo libero e le solite cyclettes e tapis roulant. Ma sono cresciute anche le richieste, anche fra le donne, di military fitness. Anche gli uomini restano fedeli ai loro esercizi: tra sollevamento pesi, potenziamento muscolare e esercizi di scarico. E&#8217; aumentata molto, ma forse pi\u00f9 per moda che per passione, almeno in alcuni casi, la richiesta di iscrizione ai corsi di Krav Maga, famoso combattimento di origine israeliana, ormai diventato comune e molto praticato&#8221;.<\/strong> Parlando di pelle e sorrisi, cos\u00ec come di corpi da modellare e scolpire, rigorosamente per la prova costume, <strong>Katia Grosso non poteva che concludere il suo viaggio, parlando di moda. I colori di adesso sono quelli legati alla leggerezza, alla fantasie floreali, all&#8217;unire l&#8217;eleganza con la seduzione. Ci si scopre di pi\u00f9, ci si mostra con maggiore felicit\u00e0 e le donne, si sa bene, nell&#8217;esaltazione della loro bellezza e felicit\u00e0 non vogliono fare brutte figure. Ecco allora, vestiti di leggerezza. Complimenti a Katia Grosso per la dovizia di particolari con cui c&#8217;ha accompagnato lungo questo viaggio, sospinti dalla leggerezza della primavera.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Vestiti di leggerezza. Dopo essersi, seppur con fatica e vigore, liberata dalla stretta prigionia del &#8220;generale&#8221; inverno e delle<\/p>\n","protected":false},"author":22,"featured_media":20676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-20675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20675"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20676"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}