{"id":207000,"date":"2023-07-19T11:54:55","date_gmt":"2023-07-19T09:54:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=207000"},"modified":"2023-07-19T11:54:55","modified_gmt":"2023-07-19T09:54:55","slug":"operaio-scomparso-da-un-mese-lappello-sui-social-diffuso-da-klaus-davi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/operaio-scomparso-da-un-mese-lappello-sui-social-diffuso-da-klaus-davi\/","title":{"rendered":"Operaio scomparso da un mese, l&#8217;appello sui social diffuso da Klaus Davi"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; A un mese dalla scomparsa, Klaus Davi torna sulla vicenda di Gaetano Crea, scomparso un mese fa. <strong>Dal 18 giugno non si hanno pi\u00f9 notizie di lui<\/strong>. Gli inquirenti sono al lavoro e la famiglia \u00e8 in apprensione.<\/p>\n<p>Davi, avrebbe scoperto un dettaglio non da poco,: Crea, lavoratore stimato, era impegnato come addetto delle societ\u00e0 di pulizie attive in modalit\u00e0 di appalto presso le ferrovie di Reggio Calabria. Tutto da verificare che le due vicende siano collegate, ma &#8220;questa \u00e8 l&#8217;occasione per riaccendere i riflettori su un contesto denunciato come pericoloso e malsano da molti operai che ho intervistato gi\u00e0 nel luglio 2017&#8221;, ha ribadito Klaus Davi.<\/p>\n<p>Il giornalista ha diffuso un annuncio con indicati numeri di <strong>telefono cellulare<\/strong> (<strong>371 5185486<\/strong>) e fisso (<strong>02 860542<\/strong>) e un indirizzo mail (<em>klausdavi@virgilio.it<\/em>) per chi avesse notizie di Gaetano. &#8220;L&#8217;importante \u00e8 che non scenda il silenzio e chiss\u00e0 che qualcuno non si decida a parlare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; REGGIO CALABRIA &#8211; A un mese dalla scomparsa, Klaus Davi torna sulla vicenda di Gaetano Crea, scomparso un mese fa. Dal 18 giugno non si hanno pi\u00f9 notizie di lui. Gli inquirenti sono al lavoro e la famiglia \u00e8 in apprensione. Davi, avrebbe scoperto un dettaglio non da poco,: Crea, lavoratore stimato, era impegnato [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":207005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-207000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=207000"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/207005"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=207000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=207000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=207000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}