{"id":20703,"date":"2013-04-05T12:30:16","date_gmt":"2013-04-05T10:30:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20703"},"modified":"2023-01-17T13:18:29","modified_gmt":"2023-01-17T12:18:29","slug":"7884-ip-rogliano-ovest-un-pieno-di-licenziamenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7884-ip-rogliano-ovest-un-pieno-di-licenziamenti\/","title":{"rendered":"Ip Rogliano Ovest, un pieno di licenziamenti"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Al distributore non si fa pi\u00f9 il pieno. Di stipendi.<strong> Il vento della crisi s&#8217;abbatte anche sulle stazioni di servizio di servizio. <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>Tre dipendenti di un&#8217;area di servizio, precisamente l&#8217;Ip di Rogliano Ovest, sono stati licenziati. Ma la scure dei tagli, non \u00e8 l&#8217;unico problema con cui i benzinai, da mesi, sono costretti a fare i conti. Sono otto mesi, infatti, che non percepiscono lo stipendio. Sono tredici i dipendenti che si sono ritrovati, \u00e8 il caso di dirlo, al verde. Si tratta di un capo piazzale, di nove addetti alle pompe e di tre banconisti. I lavoratori, stanchi di aspettare risposte che non arrivano da tempo, hanno inscenato un sit in di protesta davanti la stazione di servizio.<\/strong> Tutti e tredici sono stati messi in cassa integrazione da marzo a dicembre dello scorso anno e reclamano dall&#8217;Inps il &#8220;pieno&#8221; dell&#8217;ultimo semestre del 2012. <strong>A sostenerli nella loro protesta, la Filcams Cgil. Il sit in, ha creato un p\u00f2 di disagio, rallentando l&#8217;erogazione della benzina e dilatando un p\u00f2 i tempi di rifornimento. Ma nessun automobilista ha protestato. Anzi, in tanti, dopo aver fatto benzina, si sono avvicinati ai m,anifestanti per conoscere le loro ragioni e garantirgli piena solidariet\u00e0.<\/strong> Nel racconto dei tredici manifestanti c&#8217;\u00e8 tutta la rabbia per una vertenza paralizzata.<strong> &#8220;Tutti i tentativi di aprire un dialogo e un tavolo di confronto e di trattativa con la propriet\u00e0, si sono rivelati inutili. Tentativi, puntualmente caduti nel vuoto. Sollecitazioni di pagamento inoltrate a chi di dovere, ma rispedite al mittente. Anzi, sostengono amareggiati &#8211; la propriet\u00e0, come risposte alle nostre sollecitazioni e a quelle del sindacato, ha dato tre licenziamenti, firmati prima di Pasqua. Come dire al danno anche la beffa&#8221;.<\/strong> Al termine del sit in, Maria Bruno, segretario della Filcams Cgil, ha assunto la tutela dei lavoratori.<strong> &#8220;Non ce la facciamo pi\u00f9, vogliamo solo giustizia e il riconoscimento del nostro sacrosanto diritto di lavorare. Alla propriet\u00e0 non stiamo chiedendo un piacere, stiamo solo chiedendo il pagamento di quello che ci spetta. Abbiamo avuto tutta la comprensione possibile ed immaginabile, per cercare una soluzione o aprire un dialogo. Ma la nostra disponibilit\u00e0 non \u00e8 stata n\u00e8 apprezzata, n\u00e8 presa in considerazione. Ora basta&#8221;. Ora il sindacato ha deciso di convocare a breve i lavoratori, per definire insieme gli obiettivi strategici da programmare, al fine di rivendicare la pronta tutela dei dipendenti, con la riassunzione, immediata, dei tre licenziati e con il pagamento della liquidazione e delle mensilit\u00e0 ordinarie e straordinarie, maturate dai lavoratori. Nel frattempo, la vertenza \u00e8 stata inoltrata anche al prefetto di Cosenza Raffaele Cannizzaro. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Al distributore non si fa pi\u00f9 il pieno. Di stipendi. Il vento della crisi s&#8217;abbatte anche sulle stazioni di servizio di servizio.<\/p>\n","protected":false},"author":22,"featured_media":20704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-20703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20703"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20704"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}