{"id":207258,"date":"2023-07-21T15:42:11","date_gmt":"2023-07-21T13:42:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=207258"},"modified":"2023-07-21T15:42:11","modified_gmt":"2023-07-21T13:42:11","slug":"dimensionamento-scuola-la-calabria-perde-79-autonomie-29-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/dimensionamento-scuola-la-calabria-perde-79-autonomie-29-a-cosenza\/","title":{"rendered":"Dimensionamento scuola, la Calabria perde 79 autonomie: -29 a Cosenza"},"content":{"rendered":"<p>CATANZARO &#8211; La giunta regionale della Calabria ha approvato le linee guida per il <strong>dimensionamento della rete scolastica calabrese<\/strong> per il triennio che inizier\u00e0 nel 2024\/2025 e che avr\u00e0 79 autonomie scolastiche in meno: &#8211;<strong>14 per la provincia di Catanzaro, -8 Crotone, -29 Cosenza, -11 Vibo Valentia e -17 la Citt\u00e0 metropolitana di Reggio Calabria<\/strong>.<\/p>\n<p>&#8220;Siamo riusciti &#8211; ha detto nel corso di un incontro con la stampa il presidente Roberto Occhiuto &#8211; ad ottenere un grande risultato. <strong>Molte Regioni, specie quelle del sud, si sono lamentate della riduzione delle autonomie.<\/strong> Grazie al lavoro svolto dall&#8217;assessore Giusi Princi<strong> la Calabria manterr\u00e0 le autonomie soprattutto nei comuni che ne hanno pi\u00f9 bisogno<\/strong>. Penso a San Luca, a Plat\u00ec, dove c&#8217;\u00e8 necessit\u00e0 di un grande investimento nella formazione scolastica perch\u00e9 \u00e8 un investimento nella formazione delle coscienze&#8221;. &#8220;\u00c8 la dimostrazione del fatto &#8211; ha spiegato Occhiuto &#8211; che quando le Regioni lavorano in collaborazione con il governo, soprattutto quando hanno assessori bravi come la vicepresidente Princi, i problemi si risolvono con grande beneficio per i cittadini anche nell&#8217;ambito della scuola&#8221;. \u00f9<\/p>\n<p>I dettagli relativi alle linee guida sul<strong> Piano di dimensionamento<\/strong> e sulla programmazione dell&#8217;offerta formativa per il prossimo triennio, oggetto della delibera di Giunta, sono stati esposti dalla vicepresidente e assessora all&#8217;istruzione Giusi Princi: &#8220;<strong>L&#8217;ultimo dimensionamento scolastico della Calabria &#8211; ha sottolineato &#8211; risale al 2012<\/strong>. Il documento, avallato da tutte le componenti, Ufficio scolastico regionale e sindacati, va ad abbattere i vincoli dimensionali che dopo il periodo Covid sono di 600 e 400 alunni, noi invece con il numero delle autonomie che ci sono state assegnate a livello nazionale, che sono 281, quindi 79 in meno rispetto all&#8217;attuale situazione, abbattendo i vincoli dimensionali <strong>riusciamo a salvaguardare soprattutto le aree interne<\/strong> maggiormente a rischio spopolamento, povert\u00e0 educativa e dispersione scolastica&#8221;.<\/p>\n<p>Il nuovo documento prevede la<strong> possibilit\u00e0 di costituire dei poli liceali, dei poli tecnici professionali ed educativi<\/strong>. &#8220;Tutto questo &#8211; ha aggiunto Giusi Princi &#8211; prevedendo anche i servizi per l&#8217;infanzia perch\u00e9 sappiamo anche in tal senso come \u00e8 critica la situazione. Curveremo, dunque l&#8217;esigenza in base alla necessit\u00e0 dei territori. Il documento \u00e8 proiettato verso la grande centralit\u00e0 che vogliamo garantire all&#8217;istruzione e al mondo scolastico in Calabria attraverso la compensazione faremo in modo che nei grossi centri sar\u00e0 possibile avere istituzioni scolastiche che superino o rimangano nelle mille unit\u00e0, mentre nelle aree interne sar\u00e0 possibile avere dei tetti pi\u00f9 bassi a salvaguardia del diritto allo studio&#8221;.<\/p>\n<p><strong>Alle Province e ai Comuni sar\u00e0 garantito un portale<\/strong> come osservatorio che permetter\u00e0 ad ogni realt\u00e0 di avere una l<strong>ettura georeferenziata delle criticit\u00e0 dei propri territori.<\/strong> Da aree con zero criticit\u00e0 indicate in verde ad aree maggiormente critiche indicate in rosso, provincia per provincia, comune per comune. &#8220;La Regione &#8211; ha concluso la vicepresidente &#8211; subentrer\u00e0 alla fine, solo per approvare i documenti e i piani delle Province e della Citt\u00e0 metropolitana di Reggio Calabria, ma qualora non ci fosse coerenza nei loro piani con le linee guida, interverremo a modificare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; La giunta regionale della Calabria ha approvato le linee guida per il dimensionamento della rete scolastica calabrese per il triennio che inizier\u00e0 nel 2024\/2025 e che avr\u00e0 79 autonomie scolastiche in meno: &#8211;14 per la provincia di Catanzaro, -8 Crotone, -29 Cosenza, -11 Vibo Valentia e -17 la Citt\u00e0 metropolitana di Reggio Calabria. [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":206299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-207258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=207258"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/206299"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=207258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=207258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=207258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}