{"id":207308,"date":"2023-07-22T12:57:34","date_gmt":"2023-07-22T10:57:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=207308"},"modified":"2023-07-22T12:57:34","modified_gmt":"2023-07-22T10:57:34","slug":"caronte-bis-arriva-il-nuovo-anticiclone-con-temperature-fino-a-48-gradi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/caronte-bis-arriva-il-nuovo-anticiclone-con-temperature-fino-a-48-gradi\/","title":{"rendered":"&#8216;Caronte bis&#8217;, arriva il nuovo anticiclone con temperature fino a 48 gradi"},"content":{"rendered":"<p>ROMA &#8211; Il clima italiano \u00e8 sempre pi\u00f9 tropicale e all&#8217;inizio della settimana \u00e8 in arrivo un nuovo anticiclone che porter\u00e0 ancora<strong> caldo estremo sulla penisola<\/strong>. E&#8217; la previsione di <strong>Mattia Gussoni, meteorologo del sito www.iLMeteo.it<\/strong>. &#8220;E&#8217; in arrivo &#8216;Caronte Bis&#8217;, una nuova fiammata africana con l&#8217;anticiclone che &#8211; afferma il meteorologo &#8211; porter\u00e0 temperature oltre i 45\u00b0C anche in Puglia e picchi di 48\u00b0C, di nuovo, in Sardegna. E tutto questo calore scalder\u00e0 anche i nostri mari&#8221;.<\/p>\n<p>Il Centro Euro-Mediterraneo sui Cambiamenti Climatici prevede infatti per fine luglio una temperatura dell&#8217;acqua di 32\u00b0C, pi\u00f9 calda anche di quella del Mar dei Caraibi. Si tratta, spiega l&#8217;esperto, del &#8220;gravissimo problema delle Mhw, le Ondate di Calore Marino, sempre pi\u00f9 frequenti con <strong>l&#8217;acqua del mare che bolle.<\/strong> Ce ne accorgiamo facendo il bagno in Italia ormai da anni, ma questo 2023 sembra ancora peggio del 2022&#8243;.<\/p>\n<p>Sulla terraferma invece, oltre al calore, aggiunge, &#8220;viviamo anche il <strong>disastro degli eventi estremi provocati dal Riscaldamento globale<\/strong>: mai come in questo mese abbiamo capito che, dopo una fase di Anticiclone Africano a 40-48\u00b0C, arrivano sempre puntuali i <strong>nubifragi, la grandine distruttiva e le alluvioni<\/strong>. I fenomeni estremi, infatti, sono <strong>collegati strettamente al caldo ed all&#8217;umidit\u00e0<\/strong>: pi\u00f9 una massa d&#8217;aria \u00e8 calda e maggiore \u00e8 l&#8217;umidit\u00e0 contenuta, umidit\u00e0 che va a formare gocce di pioggia, chicchi di grandine e rovesci temporaleschi. Inoltre, pi\u00f9 \u00e8 calda l&#8217;aria e pi\u00f9 \u00e8 leggera: in questo modo il vapore sale fino a 10 km di altezza dentro i cumulonembi, gela e causa grandine grossa anche 10 cm come successo negli ultimi giorni in Pianura Padana&#8221;.<\/p>\n<p>Insomma, caldo africano, grandinate record, venti tempestosi: \u00e8 il nuovo clima con il Riscaldamento globale, che porta a un&#8217;Italia sempre pi\u00f9 tropicale. E l&#8217;emergenza non \u00e8 finita: \u00e8 in arrivo Caronte Bis, <strong>con l&#8217;inizio della nuova settimana che sar\u00e0 ancora pi\u00f9 rovente<\/strong>.<\/p>\n<p>Per quanto riguarda le prossime ore, intanto, \u00e8 previsto comunque un sabato temporalesco al Nord-Est, un leggero calo termico al Centro e<strong> ancora tantissimo sole e caldo al Sud.<\/strong> Domenica il tempo sar\u00e0 pi\u00f9 stabile e soleggiato e le temperature torneranno a salire anche al Nord.<\/p>\n<p>La <strong>nuova settimana<\/strong> vivr\u00e0 poi il bis di Caronte e, per adesso, perdurer\u00e0 il caldo estremo. <strong>NEL DETTAGLIO<\/strong> Sabato 22. Al nord: altri temporali, specie ad Est. Al centro: bel tempo salvo qualche nube in transito. Al sud: sole e ancora caldo intenso. Domenica 23. Al nord: soleggiato e caldo. Al centro: soleggiato e molto caldo. Al sud: sole e caldo intenso, in ulteriore intensificazione. <strong>Luned\u00ec 24<\/strong>. Al nord: soleggiato e molto caldo. Al centro: soleggiato e caldo fino a 40\u00b0C. <strong>Al sud: sole e caldo estremo fino a 45-48\u00b0C<\/strong>. Tendenza: fiammata africana specie verso le Isole Maggiori e l&#8217;estremo Sud, massime diffuse di 45\u00b0C ad inizio settimana con picchi di 48\u00b0C.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Il clima italiano \u00e8 sempre pi\u00f9 tropicale e all&#8217;inizio della settimana \u00e8 in arrivo un nuovo anticiclone che porter\u00e0 ancora caldo estremo sulla penisola. E&#8217; la previsione di Mattia Gussoni, meteorologo del sito www.iLMeteo.it. &#8220;E&#8217; in arrivo &#8216;Caronte Bis&#8217;, una nuova fiammata africana con l&#8217;anticiclone che &#8211; afferma il meteorologo &#8211; porter\u00e0 temperature [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":206605,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-207308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=207308"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/206605"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=207308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=207308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=207308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}