{"id":207552,"date":"2023-07-29T12:23:32","date_gmt":"2023-07-29T10:23:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=207552"},"modified":"2023-07-29T11:59:42","modified_gmt":"2023-07-29T09:59:42","slug":"a-trebisacce-la-giornata-ecologica-400-posacenere-tascabili-per-le-cicche","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-trebisacce-la-giornata-ecologica-400-posacenere-tascabili-per-le-cicche\/","title":{"rendered":"A Trebisacce la giornata ecologica, 400 posacenere tascabili per le cicche"},"content":{"rendered":"<p>TREBISACCE (CS) \u2013<strong> Quattrocento posacenere portatili da spiaggia<\/strong> da distribuire tra cittadini temporanei e residenti, cos\u00ec da difendere e tutelare l\u2019ambiente e soprattutto le spiagge dalle cicche, tra i rifiuti pi\u00f9 insidiosi ed inquinanti. Saranno distribuiti in occasione della <strong>Notte Blu<\/strong>. \u00c8 quanto fa sapere il Sindaco Alex Aurelio, ribadendo l\u2019impegno dell\u2019Esecutivo nella sensibilizzazione e nella promozione di un tema cos\u00ec importante come il contrasto <strong>all\u2019inquinamento del mare<\/strong>.<\/p>\n<p>Insieme all\u2019assessore al turismo Leonardo Petrone e al vicesindaco con delega all\u2019ambiente Nicoletta Tufaro il Primo Cittadino coglie l\u2019occasione per ringraziare l\u2019azienda Bobiost guidata da Saverio De Marco per la speciale donazione che ha voluto destinare alla comunit\u00e0 ed informare che attraverso questa iniziativa prende il via la campagna<strong> Respect the Nature<\/strong>.\u00a0Intanto dopo l&#8217;iniziativa di mercoled\u00ec scorso, ovvero la passeggiata ecologica di sensibilizzazione alla tutela del mare e al rispetto della costa, promossa dal Rotary, Rotaract e Interact Trebisacce \u2013 Alto Jonio Cosentino, <strong>domani, domenica 30 luglio<\/strong>, far\u00e0 tappa a Trebisacce l<strong>&#8216;evento Plastic Free. Alle 18,30 davanti al pontile per la giornata ecologica organizzata dal Comune in collaborazione con l\u2019Associazione Plastic Free.<\/strong> Il sodalizio ripeter\u00e0 l\u2019evento anche a met\u00e0 settembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TREBISACCE (CS) \u2013 Quattrocento posacenere portatili da spiaggia da distribuire tra cittadini temporanei e residenti, cos\u00ec da difendere e tutelare l\u2019ambiente e soprattutto le spiagge dalle cicche, tra i rifiuti pi\u00f9 insidiosi ed inquinanti. Saranno distribuiti in occasione della Notte Blu. \u00c8 quanto fa sapere il Sindaco Alex Aurelio, ribadendo l\u2019impegno dell\u2019Esecutivo nella sensibilizzazione e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":207859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-207552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=207552"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/207859"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=207552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=207552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=207552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}