{"id":20771,"date":"2013-04-08T08:10:11","date_gmt":"2013-04-08T06:10:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20771"},"modified":"2023-01-17T13:18:33","modified_gmt":"2023-01-17T12:18:33","slug":"7918-tutto-su-crotone-tasse-aziende-e-strutture-a-portata-di-click","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7918-tutto-su-crotone-tasse-aziende-e-strutture-a-portata-di-click\/","title":{"rendered":"Tutto su Crotone: tasse, aziende e strutture a portata di click"},"content":{"rendered":"<p>CROTONE &#8211; SIT, poco conosciuto, quanto prezioso.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 1;\">Il Comune di Crotone rafforza il SIT (Sistema Informativo Territoriale) attraverso la creazione di un gruppo di lavoro interno &#8220;per la migliore gestione del servizio e la fruizione dello stesso per tecnici e cittadini&#8221;. Lo si apprende da un comunicato stampa. &#8220;Il Sit &#8211; si legge &#8211; e&#8217; una struttura di grande potenzialita&#8217;, un insieme di strumenti atti ad archiviare, gestire, interrogare, trasformare e rappresentare visivamente informazioni e dati relativi al territorio e collegati ad opportuni data base. I dati provenienti dal SIT possono essere utilizzati per studiare processi ambientali, per orientare possibili processi decisionali di progettazione, che vanno dalle pianificazioni territoriali alle valutazioni di rischio di impatto ambientale, ma anche a trarre valutazione di tipo socio &#8211; economico&#8221;. &#8220;Va da se&#8217; &#8211; dichiara l&#8217;assessore all&#8217;Urbanistica Salvatore Rupert &#8211; che il Sistema Informativo Territoriale e&#8217; uno strumento di grande utilita&#8217; non solo per i tecnici dell&#8217;amministrazione ma soprattutto per i professionisti esterni e per i cittadini che accedendo ai servizi forniti dal SIT possono avere una visione completa e reale del territorio ed una serie di fondamentali informazioni Tra l&#8217;altro &#8211; aggiunge &#8211; e&#8217; un sistema che va nella direzione del contenimento della spesa permettendo di eliminare gli archivi cartacei e trasferendo dati e informazioni su supporto magnetico, favorendo una interrelazione fra dati ed argomenti di natura diversa&#8221;. Per potenziare il servizio, l&#8217;assessore Ruperto, si evidenzia nella nota, &#8220;ha promosso la creazione di un gruppo intersettoriale per ottimizzare la gestione del SIT, composto da due unita&#8217; interne afferenti ai Settori Urbanistica, Lavori Pubblici, il Servizi Ced e Tributi, cosi&#8217; da formare e introdurre all&#8217;uso e alla gestione di tutte le notizie necessarie all&#8217;attivita&#8217; amministrativa, migliorare il servizio ai cittadini attraverso l&#8217;uso di una informazione precisa e puntuale e una gestione organica e organizzata della macchina amministrativa. Il Sistema Informativo Territoriale predisposto dal Comune &#8211; e&#8217;s critto ancora &#8211; possiede una capacita&#8217; di interrogazione molto funzionale ed al tempo stesso semplice. Con un &#8220;click del mouse&#8221; tecnici e cittadini potranno accedere ad informazioni tempestive e puntuali. Tra l&#8217;altro &#8211; e&#8217; scritto infine &#8211; il potenziamento del SIT sara&#8217; fondamentale per la redazione del piano strutturale comunale e del piano spiagge&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; SIT, poco conosciuto, quanto prezioso.<\/p>\n","protected":false},"author":22,"featured_media":20772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-20771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20771"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20772"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}