{"id":207792,"date":"2023-07-28T13:03:34","date_gmt":"2023-07-28T11:03:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=207792"},"modified":"2023-07-28T13:08:49","modified_gmt":"2023-07-28T11:08:49","slug":"sartano-droga-in-casa-e-armi-e-munizioni-in-una-valigia-arrestato-insospettabile-becchino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sartano-droga-in-casa-e-armi-e-munizioni-in-una-valigia-arrestato-insospettabile-becchino\/","title":{"rendered":"Sartano: droga in casa, armi e munizioni in una valigia. Arrestato insospettabile becchino"},"content":{"rendered":"<p>TORANO CASTELLO (CS) &#8211; I carabinieri di Torano Castello, con il supporto del Nucleo Cinofili di Vibo Valentia, hanno <strong>arrestato<\/strong> un <strong>necroforo<\/strong> residente nella popolosa frazione di <strong>Sartano<\/strong>, con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti e per il possesso di un&#8217;arma bianca, diverse cartucce per pistola e fucile, e polvere da sparo mai denunciate.<\/p>\n<p>I militari hanno bussato alla porta di casa dell&#8217;insospettabile sessantenne ieri mattina e, dopo una minuziosa perquisizione domiciliare estesa anche ad una seconda abitazione, grazie al fiuto del cane \u201cBlack\u201d, hanno scoperto <strong>318 grammi di marijuana<\/strong>, 5 grammi di <strong>hashish<\/strong> ed 1,76 grammi di <strong>cocaina<\/strong>, oltre a materiale vario per il confezionamento e lo smercio in dosi della sostanze stupefacenti. Il valore della droga, se immessa sul mercato, sarebbe di circa <strong>2mila euro.<\/strong><\/p>\n<p>Il 60enne inoltre, sprovvisto di qualsiasi titolo di polizia abilitante alla detenzione di <strong>armi<\/strong> e munizioni, \u00e8 stato trovato in possesso anche di <strong>22 cartucce calibro 38<\/strong>, 20 cartucce cal. 12 e ancora 70 cartucce cal. 16. Trovato anche mezzo chilo di polvere da sparo e un pugnale lungo cm 21, mai denunciate e <strong>occultate all\u2019interno di una valigia. Il sessantenne \u00e8 stato posto ai domiciliari.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-207797 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03.jpg\" alt=\"carabinieri torano castello 03\" width=\"549\" height=\"340\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/carabinieri-torano-castello-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORANO CASTELLO (CS) &#8211; I carabinieri di Torano Castello, con il supporto del Nucleo Cinofili di Vibo Valentia, hanno arrestato un necroforo residente nella popolosa frazione di Sartano, con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti e per il possesso di un&#8217;arma bianca, diverse cartucce per pistola e fucile, e polvere da [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":207795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-207792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=207792"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/207792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/207795"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=207792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=207792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=207792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}