{"id":208206,"date":"2023-08-03T06:30:46","date_gmt":"2023-08-03T04:30:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=208206"},"modified":"2023-08-02T20:34:11","modified_gmt":"2023-08-02T18:34:11","slug":"lavoro-e-nuove-competenze-il-governo-firma-lintesa-con-fs","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lavoro-e-nuove-competenze-il-governo-firma-lintesa-con-fs\/","title":{"rendered":"Lavoro e nuove competenze: il Governo firma l&#8217;intesa con FS"},"content":{"rendered":"<p class=\"v1MsoNormal\">ROMA &#8211; Il Ministero delle Infrastrutture e dei Trasporti <strong>(MIT)<\/strong>, il Ministero dell&#8217;Istruzione e del Merito <strong>(MIM)<\/strong> e il Gruppo Ferrovie dello Stato Italiane <strong>(FS)<\/strong> hanno siglato un p<strong>rotocollo d&#8217;intesa per promuovere iniziative e collaborazioni tra mondo della scuola e mondo delle imprese<\/strong> cos\u00ec da individuare soluzioni concrete per affrontare il crescente problema del disallineamento tra le competenze richieste dalle imprese e quelle in uscita dai percorsi scolastici e formativi. Una differenza tra domanda e offerta che nel 2022 ha coinvolto oltre 2 milioni di persone e che costituisce un ostacolo alla ricerca di personale competente e preparato.<\/p>\n<p class=\"v1MsoNormal\">L&#8217;accordo interistituzionale \u00e8 stato firmato nella sede del MIT dal Vicepresidente del Consiglio dei Ministri e Ministro delle Infrastrutture e dei Trasporti <strong>Matteo Salvini<\/strong>, dal Ministro dell&#8217;Istruzione e del Merito <strong>Giuseppe Valditara<\/strong> e dall&#8217;Amministratore Delegato del Gruppo FS Italiane <strong>Luigi Ferraris<\/strong>.<\/p>\n<p class=\"v1MsoNormal\">L&#8217;intesa, di durata triennale, prevede diverse iniziative per promuovere l&#8217;informazione, il dialogo e la coprogettazione di percorsi e strumenti che rispondano all&#8217;esigenza di formare profili professionali adeguati ai<strong> fabbisogni occupazionali<\/strong>, e per promuovere progetti operativi con le scuole e le regioni. L&#8217;obiettivo \u00e8 quello di costruire progressivamente una filiera sempre pi\u00f9 integrata della formazione professionale.<\/p>\n<p class=\"v1MsoNormal\">Strumento principale il potenziamento del raccordo tra mondo della scuola e mondo delle imprese attraverso momenti di confronto, che avranno lo scopo di contribuire nel tempo a colmare il divario tra le competenze richieste dalle imprese e quelle acquisite al termine del percorso scolastico, promuovendo una maggiore consapevolezza delle prospettive occupazionali e di <strong>crescita futura per le figure professionali di settore<\/strong>. Il protocollo prevede anche la promozione di percorsi formativi che utilizzino la didattica laboratoriale per sviluppare le competenze strategiche e la creazione di un monitoraggio tra i Ministeri sulle esperienze attivate e sui risultati conseguiti.<\/p>\n<p class=\"v1MsoNormal\">Le iniziative previste dall&#8217;accordo si inseriscono in un contesto che vede il fenomeno del mismatch tra domanda e offerta di lavoro in costante crescita. Il fenomeno \u00e8 stato accelerato dalla pandemia e riguarda circa 1,3 miliardi di persone in tutto il mondo, con il rischio di riduzione della produttivit\u00e0 a livello globale del 6%. Si stima che, a livello nazionale tra il 2023 e il 2027, il 34,3% del fabbisogno occupazionale richieder\u00e0 personale con un livello di formazione terziaria, universitaria o professionalizzante e il 48,1% riguarder\u00e0 profili con un livello di formazione secondaria di secondo grado di tipo tecnico-professionale.<\/p>\n<p class=\"v1MsoListParagraphCxSpLast\">L&#8217;accordo interistituzionale segna l&#8217;inizio di una <strong>nuova cooperazione strategica e sostenibile,<\/strong> costituendo un importante passo verso la costruzione di un futuro lavorativo pi\u00f9 inclusivo, solido e allineato alle esigenze del mercato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Il Ministero delle Infrastrutture e dei Trasporti (MIT), il Ministero dell&#8217;Istruzione e del Merito (MIM) e il Gruppo Ferrovie dello Stato Italiane (FS) hanno siglato un protocollo d&#8217;intesa per promuovere iniziative e collaborazioni tra mondo della scuola e mondo delle imprese cos\u00ec da individuare soluzioni concrete per affrontare il crescente problema del disallineamento [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":208207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-208206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=208206"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/208207"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=208206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=208206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=208206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}