{"id":208228,"date":"2023-08-06T19:00:06","date_gmt":"2023-08-06T17:00:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=208228"},"modified":"2023-08-03T09:33:49","modified_gmt":"2023-08-03T07:33:49","slug":"musica-e-risate-per-lagosto-mormannese-tra-i-nomi-cirilli-dolcenera-e-loredana-berte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/musica-e-risate-per-lagosto-mormannese-tra-i-nomi-cirilli-dolcenera-e-loredana-berte\/","title":{"rendered":"Musica e risate per l&#8217;Agosto Mormannese: tra i nomi Cirilli, Dolcenera e Loredana Bert\u00e8"},"content":{"rendered":"<p>MORMANNO (CS) &#8211; Mormanno si prepara ad una nuova estate di musica e spettacolo, con grandi nomi della scena contemporanea italiana. <strong>L\u2019Agosto Mormannese<\/strong>, presentato nei giorni dall\u2019amministrazione comunale, promette di essere uno spazio di intrattenimento coinvolgente, sul quale l\u2019esecutivo guidato da Paolo Pappaterra sta puntando sempre pi\u00f9 per fare di Mormanno una tappa imperdibile dell\u2019estate calabrese.<\/p>\n<p>Da <strong>Fabrizio Bosso<\/strong>, ospite del Peperoncino Jazz Festival, al comico talentuoso <strong>Gabriele Cirilli<\/strong>, alla voce inconfondibile di <strong>Dolcenera<\/strong>, e poi <strong>Ren\u00e8e la Bulgara<\/strong>, l&#8217;estro e l&#8217;adrenalina di <strong>Loredana Bert\u00e8<\/strong> per finire con la carica coinvolgente di <strong>Paolo Belli<\/strong> sono solo alcuni dei nomi di un calendario di appuntamenti iniziati oggi con la quarta edizione di Camminiamo Mormanno, per poi immergersi gi\u00e0 negli eventi culturali di alto profilo con la tappa del Peperoncino Jazz il 7 agosto alle ore 22:00 dove al Faro Votivo si esibir\u00e0 Fabrizio Bosso insieme ad Elio Coppola Trio.<\/p>\n<p>\u00abAncora una volta &#8211; ha dichiarato il primo cittadino &#8211; faremo di Mormanno un polo attrattivo per la musica e lo spettacolo di grande profilo con i nomi pi\u00f9 importanti del panorama italiano. La nostra volont\u00e0 \u00e8 quella di <strong>consolidare sempre pi\u00f9 e meglio il nostro brand culturale &#8211;<\/strong> attrattivo per i turisti e tutti coloro che vogliono scegliere la nostra cittadina per trascorrere giornata di spensieratezza e allegria, buona musica e spettacolo, godendo delle nostre risorse naturali ed enogastronomiche che irrobustiscono l&#8217;offerta dell&#8217;ospitalit\u00e0 che mettiamo a disposizione di tutto il sud\u00bb.<\/p>\n<p>Poi <strong>la notte di San Lorenzo, il 10 agosto,<\/strong> lo spettacolo di cabaret del grande Gabriele Cirilli. Subito dopo tre giorni di <strong>Technotropia Festival<\/strong> <strong>dall\u201911 a 13 agosto<\/strong> nel centro storico dal pomeriggio alla sera, prima della inaugurazione di MormArt il <strong>12 agosto<\/strong> presso il museo del tempo. La <strong>vigilia di Ferragosto<\/strong>, invece, la voce suadente di <strong>Dolcenera<\/strong> sar\u00e0 protagonista dello spettacolo musicale in programma nell&#8217;area eventi del seminario vescovile.<\/p>\n<p>Il <strong>15 agosto<\/strong> il tradizionale appuntamento con la <strong>Madonna dell&#8217;Assunta<\/strong>, patrona di Mormanno, prima della <strong>Notte Bianca<\/strong> in programma il <strong>17 agosto<\/strong> , con la partecipazione straordinaria di \u201cQuelli che non hanno et\u00e0&#8221; e la Dj Rene\u00e8 La Bulgara e Lady Jenny Voice.<\/p>\n<p>\u00abAnche quest&#8217;anno &#8211; ha aggiunto il Consigliere con Delega allo spettacolo, Flavio De Barti &#8211; abbiamo lavorato a pieno ritmo per costruire una proposta turistica e di spettacolo che potesse accontentare tutte le fasce di et\u00e0, privilegiando qualit\u00e0 degli artisti e diversit\u00e0 di proposte, nel segno della nostra tradizione che ormai fa di Mormanno un riferimento sul territorio e non solo per gli spettacoli estivi\u00bb.<\/p>\n<p>Bellezza e fascino saranno protagonisti della serata dedicata a Miss Italia, con la elezione anche di <strong>Miss Citt\u00e0 di Mormanno<\/strong> il <strong>18 agosto alle ore 22:00<\/strong> presso la Villa San Rocco. Poi la chicca dell&#8217;estate mormannese: la regina della musica italiana <strong>Loredana Bert\u00e8<\/strong> con il concerto live della voce pi\u00f9 graffiante del panorama contemporaneo il 20 agosto prima del gran finale, sempre in musica, con l&#8217;energia di Paolo Belli e la sua band il 27 Agosto, ultimo appuntamento di una estate tutta da vivere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MORMANNO (CS) &#8211; Mormanno si prepara ad una nuova estate di musica e spettacolo, con grandi nomi della scena contemporanea italiana. L\u2019Agosto Mormannese, presentato nei giorni dall\u2019amministrazione comunale, promette di essere uno spazio di intrattenimento coinvolgente, sul quale l\u2019esecutivo guidato da Paolo Pappaterra sta puntando sempre pi\u00f9 per fare di Mormanno una tappa imperdibile dell\u2019estate [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":208230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-208228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=208228"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/208230"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=208228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=208228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=208228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}