{"id":208488,"date":"2023-08-07T10:30:24","date_gmt":"2023-08-07T08:30:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=208488"},"modified":"2023-08-07T10:59:15","modified_gmt":"2023-08-07T08:59:15","slug":"diamante-grande-successo-per-il-duo-panariello-masini-tra-musica-e-sketch-comici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/diamante-grande-successo-per-il-duo-panariello-masini-tra-musica-e-sketch-comici\/","title":{"rendered":"Diamante, grande successo per il duo Panariello-Masini tra musica e sketch comici"},"content":{"rendered":"<p>DIAMANTE (CS) &#8211; Grande successo per la prima del<strong> Teatro dei Ruderi di Diamante<\/strong> (CS) con il <strong>duo Panariello &#8211; Masini<\/strong> che ha letteralmente incantato il pubblico della riviera dei Cedri con uno spettacolo emozionante e divertente meritando a fine show la standing Ovation. <strong>\u201cLo strano incontro\u201d tra i due toscani<\/strong> ha inaugurato la ricca stagione estiva 2023 del Teatro dei Ruderi, che gi\u00e0 da subito ha presentato due colossi dello spettacolo dal vivo.<\/p>\n<p>Panariello e Masini hanno fatto scatenare gli spettatori, presenti in massa, <strong>per oltre due ore di musica d\u2019autore e sketch comici,<\/strong> un abbinamento strano ma vincente, difatti il duo \u00e8 risultato originale e senza precedenti. I due artisti non hanno fatto mancare l\u2019affetto verso la nostra terra dimostrandosi intenditori anche di molte tradizioni e usanze.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-208491 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3.jpg\" alt=\"panariello-e-masini-\" width=\"551\" height=\"367\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3.jpg 2048w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-1024x683.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-768x512.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-1536x1024.jpg 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-696x464.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-1068x712.jpg 1068w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-1920x1280.jpg 1920w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/panariello-e-masini-3-630x420.jpg 630w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><\/p>\n<p>La prima data dei Ruderi rientra nella <strong>rassegna del Tirreno Festival<\/strong>, con la rigorosa direzione artistica di <strong>Alfredo De Luca<\/strong> e realizzata con il <strong>patrocinio del comune di Diamante<\/strong>, il<strong> cofinanziamento della regione Calabria<\/strong> e la stretta collaborazione di <strong>Publiepa Srl ed E20<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-208489 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini.jpg\" alt=\"Riconoscimento-Panariello-Masini\" width=\"557\" height=\"371\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini.jpg 1620w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-1024x683.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-768x512.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-1536x1024.jpg 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-696x464.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-1068x712.jpg 1068w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/Riconoscimento-Panariello-Masini-630x420.jpg 630w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/p>\n<p>Prima della messinscena il direttore artistico Alfredo De Luca ha premiato gli artisti con il riconoscimento targato Teatro dei Ruderi come<strong> \u201cMiglior spettacolo comico-musicale 2023\u201d.<\/strong> Anche l\u2019amministrazione comunale di Diamante non ha fatto mancare il suo sostegno, il Vicesindaco Pino Pascale ha omaggiato al duo toscano i quadri dei murales pi\u00f9 rappresentativi della citt\u00e0.<\/p>\n<p>A Panariello e Masini va anche il<strong> premio ambasciatori GAL Riviera dei Cedri<\/strong>, rappresentati dal presidente Domenico Amoroso e dal vicepresidente Luigi Salsini, a dimostrazione di una forte partnership nata per la valorizzazione territoriale con eventi unici. In fine conclude De Luca : \u201cAver creato tante sinergie \u00e8 frutto del lavoro svolto in questi anni, partire bene \u00e8 fondamentale ma bisogna lavorare tanto per continuare su questo percorso\u201d.<\/p>\n<p>Appuntamento adesso con i prossimi spettacoli che si svolgeranno nell\u2019area Archeologia di Cirella Antica, il prossimo 8 agosto arriva Geolier con il soldout record.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIAMANTE (CS) &#8211; Grande successo per la prima del Teatro dei Ruderi di Diamante (CS) con il duo Panariello &#8211; Masini che ha letteralmente incantato il pubblico della riviera dei Cedri con uno spettacolo emozionante e divertente meritando a fine show la standing Ovation. \u201cLo strano incontro\u201d tra i due toscani ha inaugurato la ricca [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":208492,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[],"class_list":["post-208488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=208488"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/208488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/208492"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=208488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=208488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=208488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}