{"id":20877,"date":"2013-04-10T06:15:39","date_gmt":"2013-04-10T04:15:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20877"},"modified":"2023-01-17T13:18:39","modified_gmt":"2023-01-17T12:18:39","slug":"7972-la-falsa-solidarieta-veicolata-anche-via-sms","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7972-la-falsa-solidarieta-veicolata-anche-via-sms\/","title":{"rendered":"La falsa solidariet\u00e0, veicolata anche via sms"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> La falsa beneficienza.<strong> E&#8217; ancora forte l&#8217;eco di indignazione e di rabbia per la scoperta della rete di falsi benefattori, smantellata dai carabinieri <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>del Comando provinciale di Cosenza, diretti dal colonnello Francesco Ferace, in collaborazione con i militari dell&#8217;Arma della Compagnia di Rende, coordinati dal capitano Luigi Miele. Gli efetti devastanti della truffa che, come hanno evidenziato ieri in conferenza stampa, il procuratore aggiunto Domenico Airoma e il pm, Salvatore Di Maio, titolare dell&#8217;inchiesta, &#8220;macchia&#8221; il buon nome del volontariato, spingendo, d&#8217;ora in poi, le persone a diffidare di qualsivoglia raccolta fondi a favore di chi ha bisogno.<\/strong> Detto questo, l&#8217;indagine, nonostante la raffica di arresti, ben sette e tutti ristretti ai domiciliari, l&#8217;elevato numero di indagati quindici finora, con la probabile dilatazione a salire a ventitr\u00e8, non pu\u00f2 ancora dirsi conclusa. Il lavoro d&#8217;intelligence, fatto finora dagli inquirenti, ha fatto emergere tante, troppe anomalie, ma c&#8217;\u00e8 ancora tanto da accertare, scoprire, evidenziare. <strong>Come, per esempio, il caso dell&#8217;attivazione degli sms solidali. Strumento di efficace veicolazione solidale, di cui le assoazioni di beneficenza, godono grazie alla disposnibilit\u00e0 dei principali gestori di reti telefoniche che forniscono, a prezzi convenienti e a condizioni agevolate, l&#8217;attivazione di sms gratuiti e la concessione di telefonini, anche di ultima generazione. Su questo secondo filone, al momento in fase ancora embrionale, la Procura della Repubblica ha iniziato ad indagare, disponendo ai carabinieri un accertamento investigativo in questa direzione.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>RUOLI, PROFILI E ORGANIZZAZIONE &#8211;<\/strong> Nessuno poteva immaginare che &#8220;Il Cuore&#8221; e il &#8220;Sorriso&#8221;, erano uno specchietto per le allodole, creati ad arte, solo per veicolare la falsa beneficienza. Nessuno poteva immaginare che in quelle colorate brochure, si nascondesse il perfetto vademecum della truffa nascosta. <strong>Quelle brochure, apparse ovunque in Italia, specialmente a Olbia, Siracusa, Cosenza, Rende, Casaecchio di Reno, San Martino Buon Albergo, Verona, valmontone, Bologna, Brescia, Lamezia Terme, Roma, Napoli e tante altre citt\u00e0, hanno catturato l&#8217;interesse dell&#8217;utenza, quella sempre in prima linea quando c&#8217;\u00e8 da fare del bene.&nbsp;Ma i sette componenti dell&#8217;associazione del bene collettivo, gliene interessava poco, anzi, praticamente, nulla.<\/strong> Hanno cavalcato, l&#8217;immacolato sdentimento del buonismo, per farsi la solidariet\u00e0 da soli. <strong>La peggior solidariet\u00e0 che esiste. La truffa, per come dimostrato dagli inquirenti, era pensata, ideata e alimentata da Sandro Daniele, 62enne, imprenditore, con alle spalle qualche &#8220;chiacchiera&#8221; di troppo sulla sua fedina penale, Insieme a lui, con il ruolo apicale di presidentessa, Arianna Mauro, 20 anni, il suo fidanzato Simone Santoro, 32 anni, vecchia conoscenza delle forze dell&#8217;ordine e finito sotto i riflettori della cronaca, per essere, qualche mese, finito in manette con l&#8217;accusa di aver pestato l&#8217;avvocato Salvatore Sammarco, legale specializzato in curatele fallimentari. E poi, c&#8217;era anche il fratello di Santorto, Giuseppe, che di anni ne ha 33, cos\u00ec come anche Giuseppe Ponzano, di 30, a cui era stato assegnato il ruolo di segretario, Alessandro Di Fino, 30 anni, Manuel Intrieri di 23 e Diego Damaggio, il milanese, 34enne, pluripregiudicato e sorvegliato speciale che era il referente per il Nord. L&#8217;associazione, lo dicono i conti, almeno quelli rintracciabili dai movimenti finanziari, riscontrati sulle post pay, riusciva, in poco meno di un mese di &#8220;sollevare&#8221; 2mila euro. Peccato che finissero nelle loro tasche e non a chi ne ha bisogno. Gli arrestati si proterstano innocenti nei prossimi giorni compariranno davanti al gip per gli interrogatori.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La falsa beneficienza. E&#8217; ancora forte l&#8217;eco di indignazione e di rabbia per la scoperta della rete di falsi benefattori, smantellata dai carabinieri<\/p>\n","protected":false},"author":22,"featured_media":20878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-20877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20877"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20878"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}