{"id":20879,"date":"2013-04-10T07:23:29","date_gmt":"2013-04-10T05:23:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20879"},"modified":"2023-01-17T13:18:39","modified_gmt":"2023-01-17T12:18:39","slug":"7973-ndrangheta-un-colpo-al-cuore-dei-la-rosa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7973-ndrangheta-un-colpo-al-cuore-dei-la-rosa\/","title":{"rendered":"&#8216;Ndrangheta, un colpo al cuore dei La Rosa"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; &#8216;U Bimubu&#8217; e &#8216;Ciondolino&#8217; dietro le sbarre.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Traditi da una presunta estorsione. Sono due esponenti della &#8220;famiglia&#8221; La Rosa di Tropea, in provincia di Vibo Valentia, ed altre due persone ritenute vicine allo stesso clan, gli arrestati nell&#8217;ambito dell&#8217;operazione antimafia &#8220;Rocca Nettuno&#8221;, dal nome del noto albergo di Tropea che sarebbe stato sottoposto ad estorsione. Raggiunti da ordinanza di custodia cautelare in carcere sono il boss dell&#8217;omonimo clan Antonio La Rosa, 51 anni, detto &#8220;Ciondolino&#8221;, e suo fratello Francesco La Rosa, 42 anni, detto &#8220;U Bimbu&#8221;. Entrambi sono di Tropea. Agli arresti domiciliari sono invece finiti: Gerardo Piccolo, 41 anni, di Tropea, e Giuseppina Costa, 36 anni, di Zaccanopoli, in provincia di Vibo. Per tutti l&#8217;accusa \u00e8 quella di estorsione ai danni della struttura turistica &#8220;Rocca Nettuno&#8221;. Per Antonio La Rosa anche l&#8217;ipotesi di danneggiamento ai danni di un&#8217;autovettura dell&#8217;albergo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; &#8216;U Bimubu&#8217; e &#8216;Ciondolino&#8217; dietro le sbarre.<\/p>\n","protected":false},"author":22,"featured_media":20880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-20879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20879"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20880"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}