{"id":20887,"date":"2013-04-10T09:45:02","date_gmt":"2013-04-10T07:45:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20887"},"modified":"2023-01-17T13:18:39","modified_gmt":"2023-01-17T12:18:39","slug":"7977-5-milioni-contro-lo-spopolamento-nel-vibonese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7977-5-milioni-contro-lo-spopolamento-nel-vibonese\/","title":{"rendered":"5 milioni contro lo spopolamento nel vibonese"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>VIBO VALENTIA<\/strong> &#8211; In totale sono 9 i comuni della provincia di Vibo Valentia per i quali la Regione Calabria. ha messo a disposizione 5.043.759 euro di fondi<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">europei per contrastarne lo spopolamento. Un&#8217;importante somma che servira&#8217; a finanziare dieci operazioni (per Capistrano approvati due interventi) che aiuteranno a migliorare la qualita&#8217; della vita degli abitanti di questi piccoli centri, ma anche ad attrarre flussi turistici. E&#8217; stato, infatti, siglato l&#8217;accordo di programmazione negoziata tra l&#8217;Assessore regionale Giacomo Mancini e il partenariato di progetto del Pisl &#8220;Noi restiamo&#8221;, rappresentato da Domenico Villi&#8217;, sindaco di Vazzano comune capofila. Attraverso la firma di questo solenne atto amministrativo tutti i soggetti che compongono il partenariato di progetto hanno assunto congiuntamente, precisi obblighi rispetto all&#8217;utilizzo delle risorse &#8211; gia&#8217; ammesse a finanziamento &#8211; e alla realizzazione di interventi che favoriscano l&#8217;azione di contrasto allo spopolamento. A essere coinvolti nel Pisl sono appunto i comuni del vibonese che hanno meno di 1500 abitanti prevalentemente collocati in territorio montano e rurale (pre-Serre Vibonesi) che hanno una popolazione inferiore ai 10.000 abitanti complessivi: Capistrano, Polia, Zaccanopoli, Simbario, Pizzoni, Dasa&#8217;, Brognaturo, Vazzano e Vallelonga.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Assessore Mancini, ha siegato che, ad affliggere il territorio, sono soprattutto problemi legati all&#8217;occupazione, alla difficolta&#8217; degli anziani di accedere a servizi sanitari di base, alla carenza di strutture e attivita&#8217; per il tempo libero, soprattutto per i giovani. Ma, allo stesso tempo, questa provincia e&#8217; caratterizzata da ricchezza di natura e paesaggio e dall&#8217;artigianato tipico che costituiscono importanti punti di forza da usare come leve di sviluppo.<\/p>\n<p style=\"text-align: justify;\">Quindi, l&#8217;obiettivo del Pisl e&#8217; quello di strutturare un sistema locale idoneo ad attrarre attivita&#8217; economiche e nuovi residenti, creare opportunita&#8217; di lavoro e conseguire una maggiore coesione territoriale, valorizzando le risorse ambientali, culturali e sociali presenti nel territorio. Alla realizzazione dell&#8217;idea di forza contribuiscono numerose operazioni, tra cui quelle di Vazzano, Simbario, Dasa&#8217; e Brognaturo incentrate sulla realizzazione di centri di aggregazione polivalenti. Il Comune di Vazzano, oltre ai giovani vuole rivolgersi anche la popolazione anziana, prevedendo un servizio di assistenza domiciliare.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Assessore Mancini, ha poi aggiunto che&#8221;Pizzoni e Vallelonga, invece, vogliono ristrutturare il proprio patrimonio edilizio da concedere a canone agevolato e accogliere giovani coppie. I Comuni di Capistrano e Polia punteranno sull&#8217;ambiente con un centro di formazione per le attivita&#8217; ecostostenibili e la valorizzazione della risorsa ambientale. A Zaccanopoli si realizzera&#8217; un albergo diffuso con &#8220;vista&#8221; su Tropea e Capo Vaticano.<\/p>\n<p style=\"text-align: justify;\">E a Simbario si metteranno in moto operazioni che prevedono la concessione di spazi produttivi a canone agevolato. Per trasformare tutto questo in realta&#8217; &#8211; ha concluso Mancini &#8211; ora le procedure dovranno essere portate avanti dalle amministrazioni comunali nei tempi richiesti dalla Ue: entro il 31 dicembre di quest&#8217;anno si dovra&#8217; dare vita agli impegni giuridicamente vincolanti ed entro il 31 dicembre del 2015 dovranno essere spese tutte le risorse&#8221;. Ai comuni e alle associazioni del partenariato presenti in sala e&#8217; stato, inoltre, consegnato un attestato in ricordo di questo solenne momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; In totale sono 9 i comuni della provincia di Vibo Valentia per i quali la Regione Calabria. ha messo a disposizione 5.043.759 euro di fondi<\/p>\n","protected":false},"author":22,"featured_media":20888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-20887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20887"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20888"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}