{"id":210022,"date":"2023-08-30T21:00:02","date_gmt":"2023-08-30T19:00:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=210022"},"modified":"2023-08-30T18:48:55","modified_gmt":"2023-08-30T16:48:55","slug":"quartieri-degradati-e-sicurezza-a-rischio-comunita-gioiese-su-piazza-eranova-appelli-inascoltati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/quartieri-degradati-e-sicurezza-a-rischio-comunita-gioiese-su-piazza-eranova-appelli-inascoltati\/","title":{"rendered":"Quartieri degradati e sicurezza a rischio: comunit\u00e0 gioiese \u00absu piazza Eranova appelli inascoltati\u00bb"},"content":{"rendered":"<p>GIOIA TAURO (RC) \u2013 &#8220;Con grande dispiacere, ci troviamo nuovamente a portare all&#8217;attenzione pubblica la situazione di <strong>Piazza Eranova<\/strong>. L&#8217;abbandono, la sporcizia e il degrado che caratterizzano questo luogo non solo pregiudicano l&#8217;immagine del nostro territorio, ma sollevano anche gravi preoccupazioni riguardo la sicurezza dei residenti e, in particolare, dei bambini&#8221;. A tornare sulla situazione della zona \u00e8 Renato Bellofiore, gi\u00e0 sindaco e portavoce del Comitato \u201cIn Movimento\u201d che spiega come le &#8220;attuali condizioni della piazza potrebbero rappresentare un <strong>serio rischio per chi la frequenta<\/strong>, soprattutto per i pi\u00f9 giovani. E ci\u00f2, nonostante i numerosi appelli rivolti all&#8217;amministrazione comunale, rimane inascoltato&#8221;.<\/p>\n<p>&#8220;Da mesi, il Comitato In Movimento ha cercato di richiamare l&#8217;attenzione delle autorit\u00e0 locali sulla situazione allarmante di questo spazio pubblico. Una piazza che, vista la sua <strong>posizione strategica vicino al mare e l&#8217;assenza di spazi analoghi nelle vicinanze<\/strong>, potrebbe rappresentare un <strong>punto di riferimento fondamentale per gli abitanti<\/strong> del quartiere Mazzagatti e per gli altri quartieri limitrofi&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-210023 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1.jpg\" alt=\"piazza eranova gioia tauro 1\" width=\"580\" height=\"359\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/08\/piazza-eranova-gioia-tauro-1-356x220.jpg 356w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/p>\n<p><strong>&#8220;Le immagini pi\u00f9 recenti di Piazza Eranova sono drammatiche<\/strong>: una piazza letteralmente bruciata, sporca che testimonia l&#8217;incuria di un&#8217;area che avrebbe potuto prosperare come luogo di ritrovo e socializzazione, specialmente durante i mesi estivi. La piazza \u00e8 un cuore pulsante di vitalit\u00e0 potenziale, essendo adiacente a locali comunali, attivit\u00e0 commerciali, un palazzetto dello sport e persino una chiesa. Tuttavia, ci\u00f2 che avrebbe potuto essere un fiore all&#8217;occhiello per la comunit\u00e0, ora appare come una ferita aperta. Il <strong>degrado e l&#8217;incuria<\/strong> con cui Piazza Eranova viene trattata, nonostante gli appelli ripetuti del Comitato e dei cittadini, \u00e8 <strong>inaccettabile<\/strong>. L&#8217;abbandono in cui versa mina non solo l&#8217;estetica della zona ma anche la qualit\u00e0 della vita di chi vive e lavora nelle vicinanze.<br \/>\nDa parte del Comitato In Movimento, ci auguriamo che l&#8217;amministrazione comunale prenda finalmente provvedimenti concreti per restituire a Piazza Eranova la dignit\u00e0 che merita, trasformandola in un vero e proprio luogo di aggregazione per tutti i cittadini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO (RC) \u2013 &#8220;Con grande dispiacere, ci troviamo nuovamente a portare all&#8217;attenzione pubblica la situazione di Piazza Eranova. L&#8217;abbandono, la sporcizia e il degrado che caratterizzano questo luogo non solo pregiudicano l&#8217;immagine del nostro territorio, ma sollevano anche gravi preoccupazioni riguardo la sicurezza dei residenti e, in particolare, dei bambini&#8221;. A tornare sulla situazione [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":210024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-210022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=210022"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/210024"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=210022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=210022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=210022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}