{"id":210142,"date":"2023-09-01T13:00:04","date_gmt":"2023-09-01T11:00:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=210142"},"modified":"2023-09-01T12:40:29","modified_gmt":"2023-09-01T10:40:29","slug":"rende-scarsa-sicurezza-e-strisce-blu-dovunque-innova-rende-si-rivolge-ai-commissari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-scarsa-sicurezza-e-strisce-blu-dovunque-innova-rende-si-rivolge-ai-commissari\/","title":{"rendered":"Rende: scarsa sicurezza e strisce blu dovunque, Innova Rende si rivolge ai commissari"},"content":{"rendered":"<p>RENDE &#8211; &#8220;L\u2019insediamento dei Commissari, a seguito del doloroso, nefasto e purtroppo inevitabile scioglimento del Comune per infiltrazioni mafiose, ha portato una ventata di aria fresca e salubre all\u2019interno della casa comunale, da pi\u00f9 parti ci segnalano l\u2019umanit\u00e0 e la sensibilit\u00e0 della terna commissariale verso le tematiche che maggiormente interessano la nostra comunit\u00e0, un\u2019inversione di rotta decisamente positiva rispetto al quasi decennio della sindacatura Manna, dove la cura dell\u2019interesse particolare, troppo spesso, ha offuscato e messo da parte le reali esigenze della collettivit\u00e0. Proprio per questo vorrei porre all\u2019attenzione dei Commissari, che da poco tempo si sono insediati alla guida del Comune, due problematiche di natura diversa tra loro, ma che allo stesso tempo ledono la vivibilit\u00e0 cittadina&#8221;. A scrivere \u00e8 <strong>Francesco Midulla<\/strong>, del direttivo <strong>Innova Rende<\/strong> che punta l&#8217;attenzione su due questioni: in primis la <strong>sicurezza<\/strong>.<\/p>\n<p>Nel corso di questi mesi estivi, con le citt\u00e0 pi\u00f9 vuote, sono stati diversi <strong>tentativi di furti<\/strong> nelle <strong>abitazioni<\/strong> e nelle attivit\u00e0 della nostra area urbana. La sicurezza delle citt\u00e0 \u00e8 un tema non secondario, specie in questi momenti di forte crisi, che possono favorire forme di devianze sociale. &#8220;Come Innova Rende &#8211; prosegue Midulla &#8211; pi\u00f9 volte abbiamo affrontato questo tema, pungolando la precedente Amministrazione a <strong>ripristinare ed implementare le telecamere di video sorveglianza su tutto il territorio cittadino<\/strong>. Tale copertura andrebbe a favorire il prezioso lavoro quotidiano delle Forze dell\u2019Ordine, oltre a dare maggior tranquillit\u00e0 a cittadini e ed imprese, tanto nel centro storico quanto nelle contrade, cos\u00ec come nei quartieri centrali, nella zona Universitaria e nella zona industriale-commerciale di contrada Lecco&#8221;.<\/p>\n<h4>Strisce parcheggio a pagamento<\/h4>\n<p>&#8220;In seconda battuta &#8211; segnala Midulla &#8211; <strong>l\u2019invasione di strisce blu in citt\u00e0<\/strong>. A Rende i precedenti amministratori guidati dal <strong>sindaco Manna<\/strong>, hanno deciso di adottare tale sistema per <strong>rimpinguare le casse comunali<\/strong>, rendendo a pagamento i parcheggi su entrambi i lati delle strade. Una cosa che va contro i principi del buon senso e non tiene conto di quegli automobilisti che fanno soste brevi o degli stessi residenti che magari hanno anche un po&#8217; di difficolt\u00e0 economica. \u00c8 questa, nella fattispecie, <strong>la protesta che da tempo continuo ad ascoltare dai cittadini e dai commercianti di via Rossini, di Roges e di Commenda<\/strong>. Spero che nel breve periodo si possa ritornare ad una <strong>situazione di normalit\u00e0<\/strong>, lasciando un lato della strada libero dalle strisce blu, per permettere a tutti quelli che fanno delle soste rapide e agli stessi residenti di non incorrere in multe salate. Siamo certi che i Commissari, da autorevoli rappresentanti dello Stato prenderanno a cuore anche queste due tematiche, in modo da poter colmare tali mancanze, come da anni ormai chiedono a gran voce i cittadini di Rende&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;L\u2019insediamento dei Commissari, a seguito del doloroso, nefasto e purtroppo inevitabile scioglimento del Comune per infiltrazioni mafiose, ha portato una ventata di aria fresca e salubre all\u2019interno della casa comunale, da pi\u00f9 parti ci segnalano l\u2019umanit\u00e0 e la sensibilit\u00e0 della terna commissariale verso le tematiche che maggiormente interessano la nostra comunit\u00e0, un\u2019inversione di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":210143,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-210142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=210142"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/210143"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=210142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=210142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=210142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}