{"id":21041,"date":"2013-04-14T10:21:21","date_gmt":"2013-04-14T08:21:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21041"},"modified":"2023-01-17T13:18:48","modified_gmt":"2023-01-17T12:18:48","slug":"8061-operazione-sbagliata-risarcita-purtroppo-la-morte-ha-anticipato-la-sentenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8061-operazione-sbagliata-risarcita-purtroppo-la-morte-ha-anticipato-la-sentenza\/","title":{"rendered":"Operazione sbagliata: risarcita. Purtroppo la morte ha anticipato la sentenza"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Questione di centimetri. <strong>E&#8217; questa la trama della storia giudiziaria di C. L., pensionata cosentina, operatasi all&#8217;Ospedale<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong> dell&#8217;Annunziata di Cosenza, nel reparto di Ortopedia, e riconosciuta vittima di un caso di malasanit\u00e0, riconosciuto dai giudici del tribunale di Cosenza che hanno anche disposto il risarcimento del danno, condannando l&#8217;Azienda ospedaliera al pagamento di una cifra a diversi zeri.<\/strong> Peccato, per\u00f2, che la beneficiaria del maxi risarcimento non vedr\u00e0 un centesimo, considerato che \u00e8 deceduta prima che uscisse la sentenza. La storia in questione &#8211; per come siamo riusciti a ricostruire con la collega Katia Grosso &#8211; \u00e8 la trama dell&#8217;ennesimo caso di negligenza medica. <strong>C. L., ormai da tempo, per come racconta la sua cartella clinica e confermano i familiari e l&#8217;avvocato Massimiliano Coppa, legale di fiducia della donna e specialista in colpe mediche, era dolorante alle gambe ma viveva dignitosamente quei suoi quotidiani patimenti che la limitavano nella deamabulazione. Poi, nell\u2019ottobre del 2008 C.L., dopo aver sentito il parere degli specialisti, decise di sottoporsi ad accertamenti nel reparto di Ortopedia dell\u2019\u201cAnnunziata\u201d. I sanitari che la visitarono le diagnosticarono una \u00abcoxartrosi bilaterale delle anche con indicazione di intervento chirurgico di atroprotesi ed uso di bastone canadese\u00bb.<\/strong> Un&#8217;operazione che, a detta dei medici che l&#8217;ebbero in cuira, avrebbe dovuto restuituirle l\u2019indipendenza nei movimenti. In realt\u00e0, per\u00f2, usc\u00ec dall&#8217;ospedale con una gamba pi\u00f9 corta di quattro centimetri. Tanti, troppi per vivere quell\u2019esistenza normale che lei cercava dopo aver sofferto le conseguenze della patologia. C.L. decise di rivolgersi al Tribunale.<strong> La risposta \u00e8 arrivata negli ultimi giorni con la sentenza vergata dal giudice civile Manuela Morrone con la quale viene condannata l\u2019azienda ospedaliera a un maxi-risarcimento. Soldi, come detto, che a C.L. non serviranno pi\u00f9 perch\u00e8 nell\u2019attesa la pensionata \u00e8 morta. L\u2019incredibile trama \u00e8 contenuta nei faldoni del processo. Una storia che comincia dal ricovero della donna.<\/strong> Una decisione assunta dopo aver completato le radiografie e stabilita la necessit\u00e0 dell\u2019operazione a un arto inferiore. C.L., s\u2019affid\u00f2 all\u2019equipe di Ortopedia e traumatologia dell\u2019ospedale civile, sicura di poter risolvere il suo problema. Tuttavia, nonostante il ricorso al bisturi e l\u2019inserimento d\u2019una protesi nell\u2019anca, i dolori non s\u2019attenuarono. Il resto della vicenda \u00e8 stato messo a fuoco dall\u2019avvocato Coppa. <strong>\u00abSubito dopo l\u2019intervento, la mia assistita si sottopose ad indagini radiografiche dalle quali emerse una terribile quanto irreversibile realt\u00e0 riconducibile ad una dismetria di 4 centimetri tra l\u2019arto operato e quello sano, come ha accertato il perito nominato dal giudice\u00bb. In sostanza, la donna sarebbe entrata in sala operatoria con due gambe d\u2019identica lunghezza e ne sarebbe uscita con un arto pi\u00f9 corto dell\u2019altro. L\u2019ipotetico errore si evincerebbe dalla cartella clinica e dall\u2019accertamento tecnico eseguito dall\u2019esperto del Tribunale. \u00c8 la relazione peritale a rischiarare l\u2019humus del preteso errore in corsia. Secondo il consulente, i sanitari che effettuarono l\u2019intervento chirurgico di artroprotesi avrebbero tenuto conto solo della misurazione dell\u2019arto pi\u00f9 funzionale che non era da operare.<\/strong> Non avrebbero, invece, effettuato la giusta misurazione della gamba su cui impiantare la protesi rispetto alla lunghezza della protesi stessa.<strong> Un ipotetico errore che ha provocato l\u2019evidente dismetria dell\u2019arto operato\u00bb. Dalla consulenza, emergerebbero ipotetiche responsabilit\u00e0 nelle condotte dei sanitari che ebbero in cura, sottoposero a visita la paziente e le avrebbero cagionato l\u2019ipotetico danno irreversibile dal momento che la pensionata non si sarebbe potuta sottoporre a un secondo intervento chirurgico per una serie di ulteriori patologie concorrenti. E cos\u00ec C.L. si rivolta al Tribunale con un corposo dossier documentato dal rapporto del consulente medico legale, Berardo Cavalcanti, avanzando anche una richiesta di risarcimento del danno subito e certificato anche dal riconoscimento dell\u2019invalidit\u00e0 totale (100%) da parte della Commissione dell\u2019Asp cosentina. Risarcimento concesso dal giudice ma che non servir\u00e0 a riparare il danno. Troppo tardi, C.L., non c\u2019\u00e8 pi\u00f9. Purtroppo. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Questione di centimetri. E&#8217; questa la trama della storia giudiziaria di C. L., pensionata cosentina, operatasi all&#8217;Ospedale<\/p>\n","protected":false},"author":22,"featured_media":21042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-21041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21041"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21042"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}