{"id":210685,"date":"2023-09-09T21:26:51","date_gmt":"2023-09-09T19:26:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=210685"},"modified":"2023-09-10T15:49:33","modified_gmt":"2023-09-10T13:49:33","slug":"incidente-a-cosenza-e-deceduto-in-ospedale-il-17enne-che-era-a-bordo-della-moto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incidente-a-cosenza-e-deceduto-in-ospedale-il-17enne-che-era-a-bordo-della-moto\/","title":{"rendered":"Incidente a Cosenza, \u00e8 deceduto in ospedale il 17enne che era a bordo della moto"},"content":{"rendered":"<p>COSENZA &#8211; Si \u00e8 spento in ospedale, nel reparto di rianimazione <strong>Antonio Ruperti,<\/strong> il <strong>diciassettenne<\/strong> rimasto coinvolto in un incidente stradale avvenuto <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/grave-incidente-a-cosenza-17enne-a-bordo-di-una-moto-impatta-contro-unauto-della-polizia\">tra via Falvo e via Martorelli<\/a>. Secondo quanto emerso il ragazzo era a bordo di una motocicletta quando ha <strong>impattato prima contro un&#8217;auto della Polizia<\/strong> e finendo poi contro il <strong>muro<\/strong> di un edificio.<\/p>\n<p>Il ragazzo <strong>indossava il casco<\/strong> ma, secondo quanto emerso, non aveva la patente di guida. A a seguito dell&#8217;impatto \u00e8 stato sbalzato contro il muro di una palazzina riportando gravi lesioni interne e un trauma polmonare. Soccorso dai sanitari del 118, le sue condizioni erano gi\u00e0 critiche ed \u00e8 deceduto nel pomeriggio. Del caso sono state informate la Procura ordinaria di Cosenza e la Procura minorile di Catanzaro. Si attendono gli esiti dei rilievi condotti dalla Squadra infortunistica della Polizia locale di Cosenza utili a chiarire l&#8217;esatta dinamica dell&#8217;incidente stradale. I veicoli sono stati posti sotto sequestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si \u00e8 spento in ospedale, nel reparto di rianimazione Antonio Ruperti, il diciassettenne rimasto coinvolto in un incidente stradale avvenuto tra via Falvo e via Martorelli. Secondo quanto emerso il ragazzo era a bordo di una motocicletta quando ha impattato prima contro un&#8217;auto della Polizia e finendo poi contro il muro di un [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":177921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-210685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=210685"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/210685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/177921"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=210685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=210685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=210685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}