{"id":21165,"date":"2013-04-17T07:39:13","date_gmt":"2013-04-17T05:39:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21165"},"modified":"2023-01-17T13:18:55","modified_gmt":"2023-01-17T12:18:55","slug":"8128-operazione-lupin-sgominato-club-dellauto-rubata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8128-operazione-lupin-sgominato-club-dellauto-rubata\/","title":{"rendered":"Operazione Lupin: sgominato &#8216;club dell&#8217;auto rubata&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">VIBO VALENTIA &#8211; Rubavano ogni tipo di vettura. A tutti, anche ai carabinieri.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Tre arresti sono stati eseguiti dai carabinieri di Vibo Valentia per ricettazione e furti d&#8217;auto nel vibonese. L&#8217;inchiesta della Procura di Vibo e&#8217; denominata &#8220;Lupin&#8221; e vede indagate a piede libero anche altre due persone. Dodici in totale gli episodi delittuosi ricostruiti dagli inquirenti e fra le vittime dei furti di autovetture ci sono anche due carabinieri. L&#8217;organizzazione avrebbe agito pure fuori dai confini della provincia di Vibo Valentia. Gli arrestati sono Giuseppe Prestanicola, 37 anni, di Porto Salvo, frazione di Vino Valentia; Alex Prestanicola, 22 anni, di San Gregorio d&#8217;Ippona (Vv); Francesco Giofre&#8217;, 23 anni, pure di San Gregorio D&#8217;Ippona. Per altre due persone, che risultano indagate, il Gip Lucia Monaco non ha ritenuto di dovere mettere l&#8217;ordine d&#8217;arresto. Gli arrestati devono rispondere di associazione per delinquere finalizzata ai furti ed alla ricettazione. Coprono un arco temporale che va dal settembre 2011 al luglio 2012 gli episodi delittuosi al centro dell&#8217;operazione &#8220;Lupin&#8221; che mira a far luce su una presunta associazione a delinquere finalizzata ai furti di autovetture ed alla ricettazione di parti di autoveicoli. I ruoli degli arrestati vengono cosi&#8217; suddivisi dal gip del Tribunale di Vibo Valentia: Giuseppe Prestanicola, 37 anni, di Porto Salvo, frazione di Vibo, sarebbe il &#8220;promotore dell&#8217;organizzazione&#8221;; il fratello Alex Prestanicola, 22 anni, fidanzato con la figlia di Leone Soriano, presunto capo dell&#8217;omonimo clan di Filandari, viene invece indicato quale soggetto detito a procurare &#8220;la strumentazione necessaria per le attivita&#8217; delittuose dell&#8217;associazione&#8221;; Francesco Giofre&#8217;, 23 anni, di San Gregorio d&#8217;Ippona, avrebbe invece svolto il ruolo di &#8220;autista degli altri sodali, provvedendo inoltre a contattare ed a raggiungere i terzi ricettatori&#8221;. I delitti contestati sono stati commessi a Vibo Valentia, Cosenza, Pizzo Calabro, San Gregorio d&#8217;Ippona e Soriano Calabro. Sono stati gli accertamenti tecnici dattiloscopici effettuati dal Ris di Messina a permettere alla Procura di Vibo Valentia di risalire agli autori del furto di due autovetture appartenenti a due carabinieri in servizio al Nucleo investigativo di Vibo. Lo si evince dall&#8217;ordinanza del gip relativa all&#8217;operazione &#8220;Lupin&#8221; che ha portato stamane a tre arresti. In particolare, l&#8217;inserimento dei frammenti papillari, ovvero delleimpronte lasciate dal sudore rinvenute sulla parte posteriore dei due veicoli rubati sono stati inseriti nel sistema informatico di ricerca della banca dati delle impronte digitali e palmari. Cos\u00ec facendo, quanto al furto di una Toyota Aygo in uso ad un luogotenente dei carabinieri sono stati identificati quali autori i fratelli Giuseppe ed Alex Prestanicola, mentre relativamente al furto di un&#8217;Alfa Mito di un maresciallo dell&#8217;Arma e&#8217; stato identificato l&#8217;autore nel solo Giuseppe Prestanicola. Entrambi i furti sono stati commessi nel settembre 2011 a Vibo Valentia. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Rubavano ogni tipo di vettura. A tutti, anche ai carabinieri.<\/p>\n","protected":false},"author":22,"featured_media":21166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-21165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21165"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21166"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}