{"id":211939,"date":"2023-09-27T11:00:25","date_gmt":"2023-09-27T09:00:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=211939"},"modified":"2023-09-27T11:41:45","modified_gmt":"2023-09-27T09:41:45","slug":"colpo-ai-clan-della-ndrangheta-blitz-internazionale-di-droga-21-arresti-tra-italia-e-colombia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/colpo-ai-clan-della-ndrangheta-blitz-internazionale-di-droga-21-arresti-tra-italia-e-colombia\/","title":{"rendered":"Colpo ai clan della \u2018ndrangheta, blitz internazionale antidroga: 21 arresti tra Italia e Colombia"},"content":{"rendered":"<p>TRIESTE &#8211; Altro duro colpo inferto al narcotraffico internazionale. Dalla mattinata odierna cinquanta finanzieri, con il supporto aereo del <strong>Reparto Operativo Aeronavale di Vibo Valentia,\u00a0<\/strong>hanno dato esecuzione ad\u00a0<strong>un\u2019ordinanza di custodia cautelare in carcere che coinvolge 14 persone tra Italia e Colombia<\/strong>, che si aggiungono ad altre 7 gi\u00e0 arrestate in flagranza di reato, in seguito alle indagini condotte dal Nucleo PEF della Guardia di Finanza di Trieste, con la guida ed il coordinamento della Direzione distrettuale antimafia del capoluogo giuliano, che hanno portato al sequestro di oltre 7 quintali di cocaina.<\/p>\n<h3><strong>Colpo ai narcos colombiani<\/strong><\/h3>\n<p>Ad un anno di distanza dal sequestro di 4,3 tonnellate della medesima droga e l\u2019arresto di 38 persone, tra cui esponenti del noto \u201cClan del Golfo\u201d colombiano, a finire nel mirino degli inquirenti \u00e8 la volta dell\u2019<em>Ejercito de Liberation National\u00a0<\/em>(ELN), gruppo paramilitare rivoluzionario del paese sudamericano, i cui interessi criminali nel mercato della droga toccano gli Stati Uniti e arrivano sino in Europa. Grazie alla consolidata collaborazione con l\u2019Autorit\u00e0 Giudiziaria (<em>Fiscalia 41<\/em>) e la Polizia Colombiana, unitamente all\u2019Agenzia statunitense\u00a0<em>Homeland Security Investigations\u00a0<\/em>(HSI) e la\u00a0<em>Guardia Civil<\/em>\u00a0spagnola, oltre agli emissari del cartello sono stati individuati diversi gruppi criminali acquirenti, di origine francese, marocchina nonch\u00e9 c<strong>ollegati a importanti realt\u00e0 di \u2018ndrangheta e camorra, operanti in Lombardia, Campania e Calabria.<\/strong>\u00a0Fondamentale per il buon esito dell\u2019operazione l\u2019utilizzo di agenti \u201cundercover\u201d, che si sono insinuati nei gangli dello stoccaggio e nella distribuzione all\u2019ingrosso dello stupefacente, cos\u00ec da ricostruire i legami dei produttori sudamericani con gli acquirenti in territorio italiano ed i collegamenti tra questi e diverse figure di mediatori.<\/p>\n<h3><strong>Identificati broker, grossisti e corrieri<\/strong><\/h3>\n<p>Quindici le \u201cconsegne controllate\u201d effettuate nei primi mesi di quest\u2019anno dai finanzieri, in perfetta sinergia con l\u2019Autorit\u00e0 Giudiziaria, grazie alle quali,\u00a0<strong>oltre ad identificare\u00a0<em>broker<\/em>\u00a0e grossisti oggi attinti dalla misura cautelare, sono stati tratti in arresto anche trasportatori e fiancheggiatori di un collaudato sistema di smistamento sul territorio.<\/strong>\u00a0Oltre alla droga, il cui valore di acquisto per le organizzazioni si aggira sui 15 milioni e mezzo di euro e che sul mercato finale ne avrebbe fruttati dai 70 agli 80, sono stati\u00a0<strong>sottoposti a sequestro anche 700mila euro in contanti e 8 automezzi<\/strong>, di cui un autoarticolato: risorse e mancati introiti sottratti alle illecite ricchezze accumulate dal complesso sistema di affari del narcotraffico mondiale, senza contare le ricadute in termini di \u201ccosto sociale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRIESTE &#8211; Altro duro colpo inferto al narcotraffico internazionale. Dalla mattinata odierna cinquanta finanzieri, con il supporto aereo del Reparto Operativo Aeronavale di Vibo Valentia,\u00a0hanno dato esecuzione ad\u00a0un\u2019ordinanza di custodia cautelare in carcere che coinvolge 14 persone tra Italia e Colombia, che si aggiungono ad altre 7 gi\u00e0 arrestate in flagranza di reato, in seguito [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":211941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-211939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/211939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=211939"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/211939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/211941"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=211939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=211939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=211939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}