{"id":212612,"date":"2023-10-04T09:39:10","date_gmt":"2023-10-04T07:39:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=212612"},"modified":"2023-10-04T09:39:10","modified_gmt":"2023-10-04T07:39:10","slug":"asp-cosenza-senza-copertura-assicurativa-mazzuca-e-al-tracollo-finanziario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/asp-cosenza-senza-copertura-assicurativa-mazzuca-e-al-tracollo-finanziario\/","title":{"rendered":"Asp Cosenza senza copertura assicurativa, Mazzuca \u00ab\u00e8 al tracollo finanziario\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Non era cos\u00ec complicato prevedere che la gestione della copertura assicurativa in regime di auto-ritenzione, da parte delle singole aziende sanitarie e ospedaliere, sarebbe stato un autentico suicidio finanziario. Tant\u2019\u00e8 vero, che, sia pur provocatoriamente,<strong> avevo chiesto ad Occhiuto<\/strong> di dire pubblicamente, quante pratiche da contenzioso RCT\/O pendevano, presso le aziende sanitarie e ospedaliere della Calabria, al momento dell\u2019entrate in vigore del regime di auto-ritenzione; quante ne sono state evase fino a oggi e quali sono stati gli importi delle relative liquidazioni. Occhiuto non ha risposto&#8221;.<\/p>\n<p>Il presidente del Consiglio comunale di Cosenza spiega per\u00f2 che &#8220;<strong>la risposta \u00e8 arrivata ugualmente<\/strong>. E\u2019 arrivata, indirettamente, con la deliberazione n. 2082 del 28.settembre 2023, adottata dal Direttore Generale dell\u2019ASP di Cosenza, con la quale \u00e8 stata dichiarata <strong>l\u2019impignorabilit\u00e0 di determinate somme<\/strong>, sottoponendo a vincolo gli importi relativi alle entrate previste per il<strong> IV trimestre 2023<\/strong>, per un importo complessivo di euro <strong>287.840.349,75<\/strong>. E perch\u00e9 \u00e8 stato necessario ricorrere alla impignorabilit\u00e0 delle somme? E\u2019 stato necessario \u201cal fine di garantire la continuit\u00e0 assistenziale\u201d.<\/p>\n<p><strong>Che cosa ha messo in pericolo la garanzia circa la continuit\u00e0 assistenziale?<\/strong><\/p>\n<p>\u201cL\u2019elevato contenzioso pendente relativo a risarcimento danni derivanti da colpa professionale\u201d: cos\u00ec \u00e8, testualmente, scritto, nella richiamata deliberazione. E, allora, ci siamo: il contenzioso risarcitorio, da fronteggiare in regime di auto-ritenzione ha, letteralmente, messo in ginocchio le casse delle Azienda sanitaria provinciale di Cosenza, esponendole alla prospettiva, apocalittica, della devastante paralisi. Basti dire che, atteso l\u2019elevato contenzioso risarcitorio, senza la dichiarazione di impignorabilit\u00e0, era \u2013 addirittura \u2013 a rischio il pagamento degli stipendi in favore del dipendenti. Una sciagura. E, allora, l\u2019opzione del regime di auto-ritenzione \u2013 come era, fra l\u2019altro, intuitivamente prevedibile -, si \u00e8 rivelata una scelta strategica, semplicemente, scellerata. Ma, attenzione. La dichiarata impignorabilit\u00e0 \u00e8 solo un palliativo \u2013 tampone. il gigantesco debito derivante dall\u2019elevato contenzioso risarcitorio resta. Anzi lievita vertiginosamente, maturando, nel frattempo, gli interessi di mora. Cio\u00e8 a dire: in una regione, sottoposta al piano di rientro, il Commissario ad acta che fa? Non solo confeziona bandi di gara illegittimi, ma, poi, per riparare alla illegittimit\u00e0 dei bandi, sceglie toppe peggiori del buco. Assumendo decisioni \u2013 \u00e8 il caso della copertura assicurativa in regime di auto \u2013 ritenzione -, le quali, inevitabilmente, inesorabilmente, ineluttabilmente, producono la mostruosa ipertrofia del debito sanitario. Una gestione, scelleratamente e irresponsabilmente, fallimentare. Degna di un solo atto decoroso: rassegnare le dimissioni dalla carica di Commissario ad acta. Ma, a certe latitudini, l\u2019istituto delle dimissioni, \u00e8 un tab\u00f9 impenetrabile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Non era cos\u00ec complicato prevedere che la gestione della copertura assicurativa in regime di auto-ritenzione, da parte delle singole aziende sanitarie e ospedaliere, sarebbe stato un autentico suicidio finanziario. Tant\u2019\u00e8 vero, che, sia pur provocatoriamente, avevo chiesto ad Occhiuto di dire pubblicamente, quante pratiche da contenzioso RCT\/O pendevano, presso le aziende sanitarie e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":212616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-212612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/212612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=212612"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/212612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/212616"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=212612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=212612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=212612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}