{"id":21295,"date":"2013-04-21T19:50:21","date_gmt":"2013-04-21T17:50:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21295"},"modified":"2023-01-17T13:19:01","modified_gmt":"2023-01-17T12:19:01","slug":"8196-atletico-il-dream-team-e-un-belvedere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8196-atletico-il-dream-team-e-un-belvedere\/","title":{"rendered":"Atletico, il dream team \u00e8 un &#8230; Belvedere"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> L&#8217;Atletico \u00e8 davvero un &#8220;Belvedere&#8221;.<strong> Il gioco di parole \u00e8 il modo migliore per raccontare l&#8217;ennesima ed entusiasmante giornata<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong> di campionato di calcio a 5 femminile. La copertina della giornata spetta, senza ombra di dubbio, alla formazione tirrenica, sempre pi\u00f9 &#8220;schiaccia sassi&#8221;, sia tra le mura amiche che in trasferta. Le ragazze del Belvedere hanno, infatti, messo a segno un&#8217;altra perla, battendo, con un secco e perentorio 9-1, le resistenze della Virtus Diamante che, contro la pi\u00f9 blasonata avversaria, oltre a fare bella figura, voleva dare continuit\u00e0 alla vittoria di domenica scorsa.<\/strong> Ma sin dal fischio d&#8217;inizio, la squadra di <strong>capitan Paola Luisa Orlando, protagonista assoluta dell&#8217;incontro con una tripletta da antologia del calcio, ha spinto sull&#8217;acceleratore, stringendo alle corde le avversarie, fino a stordirle come un pugile suonato. Il capitano ha messo il &#8220;turbo&#8221;, anche nelle segnature della altre reti, realizzate da Bianca Arcuri e Maria Cristina Fiorentino (doppietta a testa, ndc) nonch\u00e8 di Celeste Girasoli e Maria Salerno che hanno messo la loro firma sul risultato rotondo.<\/strong> I tre punti permettono all&#8217;Atletico Belvedere di guardare tutti dall&#8217;alto, <strong>mantenendo a debita distanza di &#8220;sicurezza&#8221; il Cus che &#8220;asfalta&#8221; le timide resistenze del Cantinella, per 12-2. Domenica da pollice verso per il Tortora che, non sfrutta il fattore campo e si fa sorpassare per 3-4 dal Marca. La squadra cosentina con la vittoria &#8220;vendica&#8221; la gara d&#8217;andata che aveva visto il Tortora passare con facilit\u00e0 sul terreno del centro sportivo Romualdo Montagna. La sconfitta, seconda consecutiva, non pregiudica il cammino del Tortora che ha, nella forza del collettivo e nell&#8217;elevata qualit\u00e0 tecnica delle individualit\u00e0, la &#8220;benzina&#8221; per riprendere la marcia e ritornare a fare presto la voce grossa in campo a suon di vittorie e di consensi. Insomma, non c&#8217;\u00e8 che dire. E&#8217; davvero un bel campionato. Ancora tutto da vivere. <\/strong><\/p>\n<p style=\"text-align: right;\"><strong>KATIA GROSSO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;Atletico \u00e8 davvero un &#8220;Belvedere&#8221;. Il gioco di parole \u00e8 il modo migliore per raccontare l&#8217;ennesima ed entusiasmante giornata<\/p>\n","protected":false},"author":22,"featured_media":21296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-21295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21295"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21296"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}