{"id":21332,"date":"2013-04-23T05:55:38","date_gmt":"2013-04-23T03:55:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21332"},"modified":"2023-01-17T13:19:03","modified_gmt":"2023-01-17T12:19:03","slug":"8218-il-coraggio-di-denunciare-porta-a-quattro-fermi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8218-il-coraggio-di-denunciare-porta-a-quattro-fermi\/","title":{"rendered":"Il coraggio di denunciare porta a quattro fermi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Il coraggio di denunciare. <strong>Dietro il decreto di fermo di Alfonsino Falbo 42 anni, Francesco Greco, 36, Francesca Bartone, 35<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong> anni, tutti di Cosenza e Andrea Stavale, 38 anni di Bisignano, c&#8217;\u00e8 l&#8217;ordinario coraggio di due imprenditori, nel ramo del fotovoltaico, che si sono ribellati alle regole della mala, rifiutando patti ed estorsioni, finendo per pagare di persona il rifiuto con minacce e botte. I fermi, eseguiti dalla squadra Mobile di Cosenza, coordinati dal commissario capo Antonio Miglietta, sono stati disposti dai magistrati del pool antimafia della Dda di Catanzaro.&nbsp;Dietro questa storia c&#8217;\u00e8 anche un insegnamento e una verit\u00e0: per tanti imprenditori che, per paura, per vergogna o per evitare ripercussioni personali e familiari, preferiscono accettare gli accordi imposti e scegliere la strada del silenzio, ce ne sono altri, tanti altri, che, si fidano dello Stato e denunciano i soprusi, spezzando cos\u00ec il muro d&#8217;omert\u00e0 dietro il quale si nascondono i &#8220;parassiti&#8221; dell&#8217;Antistato, con l&#8217;etichetta di uomini d&#8217;onore ma che di onore hanno davvero poco, se non addirittura nulla.<\/strong> La trama di questa storia, \u00e8 purtroppo, la solita. La crisi che da tempo sta strozzando l&#8217;economica e mandando in frantumi tanti sogni imprenditoriali, s&#8217;\u00e8 abbattuta anche sui due titolari dell&#8217;azienda di impianti fotovoltaici che, non riuscivano pi\u00f9 a &#8220;stare dietro&#8221; ai pagamenti dei fornitori.<strong> I due, pensando di superare l&#8217;impasse di difficolt\u00e0, avevano deciso di rivolgersi a Francesca Bartone che, tra l&#8217;altro, consideravano amica. La 35enne, mostrando tutto il suo interesse, disse ai due di non preoccuparsi che avrebbe trovato una soluzione. Una soluzione che, secondo la denuncia dei due imprenditori e i riscontri investigativi degli agenti della squadra Mobile e dei detective del Reparto prevenzione Crimine Calabria, si \u00e8 materializzata con l&#8217;intervento di Stavale e Greco, nonch\u00e8 con l&#8217;interessamento anche di Falbo, considerato dagli inquirenti, &#8220;vicino&#8221; alla cosca Cicero. Il resto \u00e8 purtroppo cronaca. La solita. Quella che, fiutato l&#8217;affare, la cosca decide di mettere le mani sull&#8217;intero &#8220;malloppo, riprendendosi non solo il capitale con la maturazione degli interessi ma anche sull&#8217;intera azienda. Insomma un debito di 30mila e poco pi\u00f9 di euro non solo da restituire, ma la cosca voleva anche l&#8217;azienda, del valore complessivo di 1,2 milioni di euro. La richiesta, rifiutata dai due imprenditori, \u00e8 stata rispedita al mittente. Ma i quattro, il rifiuto non l&#8217;hanno preso bene. Per niente. Tanto da iniziare un vero e proprio pressing &#8220;asfissiante&#8221; sulle vittime, fatto di minacce, telefonate varie, ricatti e persino pestaggi. i\u00f9 di una volta, infatti, i due titolari dell&#8217;azienda sono stati presi a calci e pugni in faccia, nonch\u00e8 in altre parti del corpo. Seppur doloranti e sanguinanti, ai due \u00e8 stata impedito anche di recarsi in ospedale per farsi medicare. Troppo evidenti i segni del pestaggio, troppo alto il rischio che i due parlassero, troppo importante per i quattro mantenere i due imprenditori sotto la cappa di paura e terrore. Fino alla decisione dei due di uscire dall&#8217;inferno e liberarsi dai &#8220;demoni&#8221;. le vittime, infatti, hanno deciso di raccontare tutto agli agenti della squadra Mobile. Il fascicolo, considerata la presenza di personaggi vicini o intranei alle cosche, \u00e8 passato dalla Procura ordinaria alla Dda di Catanzaro. Il resto l&#8217;hanno fatto i detective della squadra Mobile e del reparto prevenzione crimine Calabria, tenendo sotto controllo l&#8217;azienda, le due vittime e i quattro. In ore e ore di intercettazioni video, telefoniche ed ambientali, c&#8217;\u00e8 tutto il compendio dell&#8217;estorsione, con tanto di minacce e avvertimenti. All&#8217;alba il blitz con il fermo dei quattro. Oggi ha vinto lo Stato, ha vinto il coraggio di denunciare. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il coraggio di denunciare. Dietro il decreto di fermo di Alfonsino Falbo 42 anni, Francesco Greco, 36, Francesca Bartone, 35<\/p>\n","protected":false},"author":22,"featured_media":21333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-21332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21332"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21332\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21333"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}