{"id":21398,"date":"2013-04-24T07:39:14","date_gmt":"2013-04-24T05:39:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21398"},"modified":"2023-01-17T13:19:07","modified_gmt":"2023-01-17T12:19:07","slug":"8254-imprenditori-basta-siamo-al-collasso-lurlo-di-confindustria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8254-imprenditori-basta-siamo-al-collasso-lurlo-di-confindustria\/","title":{"rendered":"Imprenditori: &#8220;Basta! Siamo al collasso&#8221;. L&#8217;urlo di Confindustria"},"content":{"rendered":"<p>COSENZA &#8211; L&#8217;imprenditoria cosentina alza la voce.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Una pagina di denuncia e proposte per segnalare problematiche e questioni precedute dalla parola &#8220;Basta!&#8221;. &#8220;Ripartiamo con i provvedimenti per la crescita&#8221; \u00e8 il monito lanciato da &#8220;Il Manifesto di Confindustria Cosenza&#8221;. L&#8217;Associazione degli Industriali, guidata dal Presidente Natale Mazzuca, si mobilita. per l&#8217;ennesima volta, portando alla luce &#8220;la gravissima situazione di emergenza con cui quotidianamente il sistema economico e sociale si trova a dover fare i conti e propone di ripartire con provvedimenti immediati&#8221; perche&#8217;, si sostiene, &#8220;il Paese \u00e8 in ginocchio, il Mezzogiorno rischia il collasso: il tempo e&#8217; scaduto!&#8221;. Il manifesto affronta le questioni piu&#8217; urgenti e gli interventi ineludibili che servono per garantire alle imprese di poter continuare a produrre, in attesa di una ripresa dell&#8217;economia che tende a spostarsi sempre piu&#8217; in avanti:<strong> i ritardi e le farraginosita&#8217; della burocrazia, la restrizione nella concessione di prestiti attuata dagli istituti di credito, un carico fiscale intollerabile, la scarsa dotazione e qualita&#8217; dei servizi pubblici, il modesto utilizzo dei fondi europei, i bandi di gara anomali, le procedure di aggiudicazione dei lavori pubblici riservati a pochi, i mercati chiusi e gli affidamenti in house.<\/strong> &#8220;Davanti alla lentezza dell&#8217;azione politica, a tutti i livelli, ed alla inadeguatezza delle misure attuate o semplicemente programmate rispetto alla portata ed alla valenza della crisi in atto&#8221;, Confindustria Cosenza propone &#8220;impegni di medio periodo, tesi ad affrontare i nodi strutturali che stringono il sistema territoriale ed il sistema Paese in generale&#8221;.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Il grido d&#8217;allarme lanciato dagli industriali cosentini e&#8217; il grido d&#8217;allarme di tutti gli imprenditori calabresi&#8221;. Lo afferma il Presidente di Confindustria Calabria, Giuseppe Speziali, che condivide e rilancia le questioni poste con grande forza dal Presidente di Cosenza, Natale Mazzuca, con la pubblicazione del manifesto dal titolo significativo &#8220;Basta&#8221;. &#8220;Non e&#8217; possibile &#8211; ha dichiarato Speziali &#8211; continuare ad avere un atteggiamento passivo rispetto agli effetti di una crisi che, per la Calabria, e&#8217; diventata ormai devastante: <strong>e&#8217; tempo di individuare, ed in fretta, percorsi costruttivi che siano di aiuto e supporto ad imprese e famiglie. Dai pagamenti alle imprese al welfare, dal credito agli incentivi, dalla semplificazione al corretto e pieno utilizzo dei Fondi comunitari, e&#8217; necessario &#8211; dice &#8211; accelerare il passo per dare risposte alle esigenze, ormai drammatiche, di tutto il tessuto produttivo e sociale calabrese.<\/strong> E&#8217; necessario riallacciare i fili di una filiera istituzionale interrotta da troppe settimane: Governo centrale, Regione, Enti Locali. La politica faccia in fretta e guardi ai problemi reali del Paese dando un Governo che si occupi delle cose vere e ricostituendo i punti di riferimento per il territorio. Ma oltre che di cio&#8217;, io sono anche molto preoccupato &#8211; ha sottolineato Speziali &#8211; della lentezza con cui l&#8217;Amministrazione regionale sta procedendo a varare quell&#8217;insieme di misure di intervento che da tempo sono state concertate e condivise con il partenariato regionale. Mi riferisco, in particolare, all&#8217;ultima rimodulazione del POR Calabria, con l&#8217;adesione alla terza fase del Piano di azione e coesione nazionale, nella quale sono contenute misure d&#8217;urto sia sul versante dell&#8217;occupazione che del sostegno al sistema produttivo disegnate e condivise proprio in funzione anticongiunturale (interventi di politiche attive sul lavoro complementari alla Cassa Integrazione, sostegno al capitale circolante delle imprese, garanzie fidi, misure fiscali per le aree svantaggiate, etc)&#8221;.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Per Speziali, &#8220;se si attende ancora saremo di fronte ad un deserto economico ed occupazionale che neanche terapie straordinarie ma tardive potra&#8217; piu&#8217; rianimare.<\/strong> Ed e&#8217; incomprensibile come tutta l&#8217;attenzione della politica locale sia concentrata e discuta piu&#8217; di questioni legate ad equilibri politici finalizzati al completamento della squadra di Governo regionale, che sulla necessita&#8217; di dare risposte &#8220;certe, tempestive ed efficaci&#8221; alla collettivita&#8217; calabrese. Insomma non c&#8217;e&#8217; piu&#8217; tempo da perdere, come abbiamo gia&#8217; detto recentemente a Torino: tempo scaduto! Sono certo comunque &#8211; ha concluso Speziali &#8211; che il Presidente Scopelliti sapra&#8217; individuare il percorso piu&#8217; breve ed efficace per attuare quanto di piu&#8217; utile e gia&#8217; condiviso per far fronte al momento forse piu&#8217; difficile che stanno vivendo i calabresi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;imprenditoria cosentina alza la voce.<\/p>\n","protected":false},"author":22,"featured_media":21399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-21398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21398"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21399"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}