{"id":214454,"date":"2023-10-24T19:00:55","date_gmt":"2023-10-24T17:00:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214454"},"modified":"2023-10-24T15:03:06","modified_gmt":"2023-10-24T13:03:06","slug":"spesa-su-welfare-la-calabria-e-fanalino-di-coda","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/spesa-su-welfare-la-calabria-e-fanalino-di-coda\/","title":{"rendered":"Spesa su Welfare, la Calabria \u00e8 fanalino di coda"},"content":{"rendered":"<p>ROMA &#8211; Il Welfare Italia Index 2023 misura la qualit\u00e0 della spesa, in termine di risorse e indicatori strutturali, e assegna il punteggio pi\u00f9 elevato alla pubblica amministrazione di <strong>Bolzano<\/strong> (83,3 punti). Seguono Trento (81,4 punti) e l&#8217;Emilia Romagna (76,3 punti). Al lato opposto della classifica si posizionano la Basilicata (61,4 punti), la Campania (60,4 punti) e la <strong>Calabria<\/strong> (56,7 punti).<\/p>\n<p>L&#8217;edizione 2023 segnala una <strong>costante polarizzazione nella capacit\u00e0 di risposta del sistema di welfare delle Regioni italiane<\/strong>: il <strong>divario<\/strong> tra la prima e l&#8217;ultima Regione \u00e8 infatti ancora pari a 26,6 punti. Il posizionamento delle Regioni segue l&#8217;ordine Nord- Centro-Sud con le Regioni del Nord Italia che si confermano nella parte superiore della classifica e quelle del Sud nella parte inferiore.<\/p>\n<p>La <strong>spesa in welfare in Italia<\/strong> per il <strong>2023<\/strong> salir\u00e0 a <strong>632,4 miliardi di euro<\/strong> (+3,7% rispetto al dato del 2022), includendo in questo perimetro i 3 pilastri tradizionali (<strong>Sanit\u00e0, Politiche Sociali, Previdenza) e l\u2019Istruzione<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-214476 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023.jpg\" alt=\"Welfare 2023\" width=\"668\" height=\"386\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023.jpg 926w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023-300x173.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023-768x444.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023-150x87.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023-696x402.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/Welfare-2023-727x420.jpg 727w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/p>\n<p>Secondo le stime, inserite del rapporto del Think Tank \u201cWelfare, Italia\u201d, sostenuto da Unipol e The European House &#8211; Ambrosetti, presentato oggi a Roma, la <strong>spesa previdenziale<\/strong> assorbir\u00e0 in particolare oltre la met\u00e0 delle risorse,<strong> ovvero il 50,3%<\/strong> della spesa sociale totale. A seguire, la spesa sanitaria (21,5%), quella in politiche sociali (16,9%) e la spesa in istruzione (11,3%). Considerando il dato congiunturale, rispetto al 2022 la spesa previdenziale \u00e8 in aumento del 7,1%, passando da 296,9 miliardi di euro a 317,9 miliardi di euro. La spesa sanitaria nel 2023 \u00e8 in incremento del 3,8%, rispetto allo scorso anno.<\/p>\n<h5><strong>Mattarella: \u00abstrumenti mirati per sostenere l&#8217;intero arco di vita delle persone\u00bb<\/strong><\/h5>\n<p>&#8220;L&#8217;invecchiamento di ampie fasce di cittadini interpella il contratto sociale tra le generazioni &#8211; afferma il presidente della Repubblica, Sergio Mattarella, nel messaggio inviato al convegno &#8211; l&#8217;esigenza di tutelare le maggiori fragilit\u00e0 degli anziani senza mortificare le aspirazioni dei giovani&#8221;.<\/p>\n<p>Per il Capo dello Stato &#8220;servono strumenti sempre pi\u00f9 mirati, adatti a sostenere l&#8217;intero arco di vita delle persone, a partire dai servizi di assistenza sanitaria&#8221;. Si tratta di una &#8220;responsabilit\u00e0 pubblica che non pu\u00f2 essere elusa&#8221; mentre &#8220;l&#8217;intervento e il dialogo con il settore privato rimangono preziosi&#8221; anche alla luce del principio di sussidiariet\u00e0 richiamato dalla Costituzione. &#8220;Le sfide che il nostro Paese deve affrontare su questo versante &#8211; prosegue Mattarella &#8211; sono comuni a tutta l&#8217;Unione Europea. Il pilastro europeo dei diritti sociali rappresenta la guida efficace per perseguire la lotta alle disuguaglianze e per favorire l&#8217;inclusione anche dal punto di vista occupazionale, fornendo cos\u00ec risposte ai bisogno essenziali della popolazione&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Il Welfare Italia Index 2023 misura la qualit\u00e0 della spesa, in termine di risorse e indicatori strutturali, e assegna il punteggio pi\u00f9 elevato alla pubblica amministrazione di Bolzano (83,3 punti). Seguono Trento (81,4 punti) e l&#8217;Emilia Romagna (76,3 punti). Al lato opposto della classifica si posizionano la Basilicata (61,4 punti), la Campania (60,4 [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":214458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-214454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214454"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/214458"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}