{"id":214546,"date":"2023-11-01T18:04:52","date_gmt":"2023-11-01T17:04:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214546"},"modified":"2023-11-01T18:05:27","modified_gmt":"2023-11-01T17:05:27","slug":"occupazione-cresce-nel-sud-e-anche-in-calabria-si-prevede-un-ulteriore-aumento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/occupazione-cresce-nel-sud-e-anche-in-calabria-si-prevede-un-ulteriore-aumento\/","title":{"rendered":"&#8216;Occupazione cresce nel sud e anche in Calabria: si prevede un ulteriore aumento&#8217;"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;La disoccupazione \u00e8 un dramma ma voglio fare notare che, secondo i dati Istat, l&#8217;<strong>occupazione cresce progressivamente in tutto il Sud e anche in Calabria&#8221;<\/strong>. Lo afferma il vicecapogruppo di Fratelli d&#8217;Italia alla Camera,<strong> Alfredo Antoniozzi<\/strong>. &#8220;Puglia, Calabria, Sicilia e Basilicata fanno registrare costantemente il segno pi\u00f9 &#8211; aggiunge Antoniozzi &#8211; mentre l&#8217;unica regione ferma \u00e8 la Campania: <strong>ovviamente c&#8217;\u00e8 un problema storico ma \u00e8 innegabile il trend.<\/strong> Voglio complimentarmi con l&#8217;assessore regionale al lavoro della Calabria, Giovanni Calabrese per le iniziative messe in campo sia sulla formazione che sulle start up, comprese quelle femminili, sia per l&#8217;impegno congiunto al quale stiamo partecipando, per il problema del precariato storico.<\/p>\n<p>Il mercato del lavoro anche in Calabria sta avendo importanti evoluzioni mentre ricordo che, al posto del reddito di cittadinanza, abbiamo inserito misure di sostegno e di formazione&#8221;. <strong>&#8220;Con la Zes si prevede un aumento significativo dell&#8217;occupazione &#8211; sostiene ancora il vicecapogruppo di FdI alla Camera &#8211; che porter\u00e0 benefici negli investimenti in tutta la macroarea del Sud.<\/strong> Abbiamo ancora la percentuale pi\u00f9 alta di disoccupazione ma questo accade dal dopoguerra e non deve farci dimenticare ci\u00f2 che ci dice l&#8217;Istat: il trend \u00e8 positivo ed \u00e8 destinato ad aumentare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; &#8220;La disoccupazione \u00e8 un dramma ma voglio fare notare che, secondo i dati Istat, l&#8217;occupazione cresce progressivamente in tutto il Sud e anche in Calabria&#8221;. Lo afferma il vicecapogruppo di Fratelli d&#8217;Italia alla Camera, Alfredo Antoniozzi. &#8220;Puglia, Calabria, Sicilia e Basilicata fanno registrare costantemente il segno pi\u00f9 &#8211; aggiunge Antoniozzi &#8211; mentre l&#8217;unica [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":198618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-214546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214546"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/198618"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}