{"id":214661,"date":"2023-10-25T22:30:45","date_gmt":"2023-10-25T20:30:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214661"},"modified":"2023-10-25T20:22:59","modified_gmt":"2023-10-25T18:22:59","slug":"ponte-sullo-stretto-salvini-cantieri-per-lestate-2024-e-fine-lavori-entro-il-2032","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ponte-sullo-stretto-salvini-cantieri-per-lestate-2024-e-fine-lavori-entro-il-2032\/","title":{"rendered":"Ponte sullo Stretto, Salvini: \u00abcantieri per l&#8217;estate 2024 e fine lavori entro il 2032\u00bb"},"content":{"rendered":"<p>ROMA &#8211;\u00a0 Il Ponte sullo Stretto s&#8217;ha da fare. &#8220;Ne ho gi\u00e0 parlato pi\u00f9 di una volta con il ministro competente, le sovrintendenze devono aiutare a fare le cose, non a bloccare, rallentare e complicare le cose&#8221;. Lo afferma il <strong>ministro delle Infrastrutture e dei Trasporti, Matteo Salvini,<\/strong> all&#8217;assemblea nazionale dell&#8217;Anci a Genova, parlando del Ponte sullo Stretto di Messina.<\/p>\n<p><strong>&#8220;Se deve arrivare uno da Milano, che fa il segretario della Lega, dopo 52 anni a fare il ponte tra Sicilia, Calabria ed Europa, per me \u00e8 motivo di vanto&#8221;<\/strong>, dichiara Salvini indicando ancora una volta l&#8217;obiettivo &#8220;di aprire i <strong>cantieri entro l&#8217;estate 2024&#8243;<\/strong>. &#8220;C&#8217;\u00e8 l&#8217;accordo &#8211; aggiunge degli enti locali, delle Regioni, delle categorie produttive, degli agricoltrori, dei commercianti, degli imprenditori, degli studenti, delle universit\u00e0. E&#8217; chiaro che velocizza e toglie CO2 dall&#8217;aria, spero che non ci siano i professionisti del no in servizio continuativo&#8221;.<\/p>\n<p>Ci saranno anche delle scuole professionali sul territorio per le aziende che lavoreranno al Ponte sullo Stretto. Lo ha detto il vicepremier e ministro Matteo Salvini, in occasione del convegno annuale di Anceferr. <strong>Salvini ha ribadito di puntare a far s\u00ec che il ponte sia percorribile nel 2032<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211;\u00a0 Il Ponte sullo Stretto s&#8217;ha da fare. &#8220;Ne ho gi\u00e0 parlato pi\u00f9 di una volta con il ministro competente, le sovrintendenze devono aiutare a fare le cose, non a bloccare, rallentare e complicare le cose&#8221;. Lo afferma il ministro delle Infrastrutture e dei Trasporti, Matteo Salvini, all&#8217;assemblea nazionale dell&#8217;Anci a Genova, parlando del [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,1],"tags":[19],"class_list":["post-214661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214661"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202082"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}