{"id":214663,"date":"2023-10-25T20:10:33","date_gmt":"2023-10-25T18:10:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214663"},"modified":"2023-10-25T20:10:33","modified_gmt":"2023-10-25T18:10:33","slug":"citta-unica-confronto-con-il-ministero-dei-trasporti-mezzi-nuovi-e-piu-efficienti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/citta-unica-confronto-con-il-ministero-dei-trasporti-mezzi-nuovi-e-piu-efficienti\/","title":{"rendered":"Citt\u00e0 unica, confronto con il Ministero dei Trasporti: \u00abmezzi nuovi e pi\u00f9 efficienti\u00bb"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;La direzione \u00e8 quella di garantire una nuova mobilit\u00e0 sul territorio con un unico committente al fine di offrire all&#8217;utente un trasporto sempre pi\u00f9 regolare, ed inoltre con basso impatto ambientale. Una citt\u00e0 nuova che superando i centomila abitanti potr\u00e0 contare sull&#8217;economia di scala generata con una sola azienda di trasporto pubblico locale, una nuova programmazione e la possibilit\u00e0 data con il rinnovo dell&#8217;intera flotta mezzi&#8221;. E&#8217; quanto affermano, in una dichiarazione congiunta, la presidente della I Commissione consiliare &#8216;Affari istituzionali <strong>Luciana De Francesco<\/strong> e il consigliere <strong>Pierluigi Caputo<\/strong> tra i firmatari della proposta di legge sulla<strong> fusione dei comuni di Cosenza, Castrolibero e Rende.<\/strong><\/p>\n<p>&#8220;Oggi \u00e8 stato audito &#8211; \u00e8 detto in una nota &#8211; il <strong>dirigente del Ministero delle Infrastrutture e dei Trasporti Angelo Mautone<\/strong> referente per le strutture della direzione generale del trasporto pubblico locale e regionale e la mobilit\u00e0 pubblica sostenibile. Dalla sua esposizione il dirigente ha sottolineato i<strong> numerosi vantaggi derivanti dall&#8217;accorpamento dei centri abitati del cosentino<\/strong>. Sotto la lente d&#8217;ingrandimento, la situazione trasporti&#8221;.<\/p>\n<p>&#8220;Sar\u00e0 prevista una nuova figura tecnica, il Mobility Manager &#8211; sostengono De Francesco e Caputo &#8211; che lavorer\u00e0 per il territorio ponendo l&#8217;attenzione sulla mobilit\u00e0 di studenti, lavoratori e cittadini, superando ogni criticit\u00e0 che oggi risuonano come inefficienza dei trasporti, sempre pi\u00f9 frammentati, del tutto scollegati. Oltre all&#8217;immediato risparmio sulle casse pubbliche e pertanto <strong>minore impatto sul costo trasporti e derivanti tassazioni,<\/strong> la Citt\u00e0 Unica potr\u00e0 attingere oltre che ai finanziamenti regionali e lavorare su appositi bandi potr\u00e0 contare su finanziamenti diretti dal Ministero.<\/p>\n<p>Si guarda anche alle piste ciclabili, all&#8217;ambiente, al collegamento sempre pi\u00f9 importante e fondamentale sotto ogni aspetto con l&#8217;Universit\u00e0 della Calabria. Ateneo tra i primi d&#8217;Italia e sempre maggiore attrattore sul territorio di migliaia di studenti. Una grande opportunit\u00e0 per tutti i futuri cittadini della <strong>Grande Cosenza<\/strong>, per l&#8217;intera provincia che si muove verso questo territorio, per lavoro, per studio, per i numerosi uffici pubblici presenti nell&#8217;area urbana, per salute con l&#8217;Hub Ospedaliero dell&#8217;Annunziata di Cosenza&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;La direzione \u00e8 quella di garantire una nuova mobilit\u00e0 sul territorio con un unico committente al fine di offrire all&#8217;utente un trasporto sempre pi\u00f9 regolare, ed inoltre con basso impatto ambientale. Una citt\u00e0 nuova che superando i centomila abitanti potr\u00e0 contare sull&#8217;economia di scala generata con una sola azienda di trasporto pubblico [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":214665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-214663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214663"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/214665"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}