{"id":214729,"date":"2023-10-26T11:04:52","date_gmt":"2023-10-26T09:04:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214729"},"modified":"2023-10-26T11:04:52","modified_gmt":"2023-10-26T09:04:52","slug":"da-torremezzo-a-roma-per-partecipare-ad-avanti-un-altro-lesperienza-di-erika","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/da-torremezzo-a-roma-per-partecipare-ad-avanti-un-altro-lesperienza-di-erika\/","title":{"rendered":"Da Torremezzo a Roma per partecipare ad &#8216;Avanti un altro&#8217;. L&#8217;esperienza di Erika"},"content":{"rendered":"<p>FALCONARA ALBANESE (CS) &#8211; Si chiama <strong>Erika Bruno, ha 25 anni<\/strong> e lo scorso 24 ottobre \u00e8 partita alla volta degli studi Studi Elios Mediaset per partecipare al fortunato programma televisivo condotto da <strong>Paolo Bonolis<\/strong>. \u00abHo conosciuto tante persone del settore, e sono entrata subito nel cuore dei produttori che mi hanno consentito di registrare il primo giorno\u00bb &#8211; racconta emozionata Erika alla nostra redazione.<\/p>\n<p>\u00abCi saranno un sacco di <strong>sorprese<\/strong> e tantissime <strong>risate<\/strong>. Sono stata notata e accolta positivamente e ho avuto anche, se cos\u00ec posso dire, l&#8217;opportunit\u00e0 di instaurare subito un rapporto molto amichevole con Bonolis\u00bb.<\/p>\n<p>Erika Bruno \u00e8 una ballerina della scuola di danza &#8220;Accademia Dance Art &#8211; di Rosalia Romagno&#8221; e balla da quando aveva solo due anni. Una passione che continua a coltivare. \u00abHo partecipato anche a diverse sfilate e concorsi, tra cui Miss Italia, nel 2016, dove sono arrivata fino alla finalissima regionale\u00bb. Nata a Paola ma residente a Torremezzo di Falconara Albanese, Erika ha voluto raccontare la sua nuova ed entusiasmante esperienza da concorrente di Avanti un altro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-214735 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2.jpg\" alt=\"erika bruno paola avanti altro2\" width=\"481\" height=\"298\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/10\/erika-bruno-paola-avanti-altro2-356x220.jpg 356w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FALCONARA ALBANESE (CS) &#8211; Si chiama Erika Bruno, ha 25 anni e lo scorso 24 ottobre \u00e8 partita alla volta degli studi Studi Elios Mediaset per partecipare al fortunato programma televisivo condotto da Paolo Bonolis. \u00abHo conosciuto tante persone del settore, e sono entrata subito nel cuore dei produttori che mi hanno consentito di registrare [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":214734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[],"class_list":["post-214729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214729"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/214734"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}