{"id":214868,"date":"2023-10-27T17:00:21","date_gmt":"2023-10-27T15:00:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=214868"},"modified":"2023-10-27T17:16:47","modified_gmt":"2023-10-27T15:16:47","slug":"sanitacs-tagliocs-sui-fitti-asp-cosenza-e-acquista-uno-stabile-dallinps","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sanitacs-tagliocs-sui-fitti-asp-cosenza-e-acquista-uno-stabile-dallinps\/","title":{"rendered":"Sanit\u00e0, Asp Cosenza vuole risparmiare sui fitti passivi e acquista uno stabile dall&#8217;Inps"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Questa mattina alle ore 10.30, dinanzi al Notaio Italo Alessio Scornajenchi, <strong>l\u2019Asp di Cosenza<\/strong> in persona del suo Direttore Generale Dott. Antonio Graziano, ha <strong>acquistato dall\u2019Inps<\/strong>, rappresentata dal Direttore Regionale dott. Giuseppe Greco, <strong>un prestigioso stabile<\/strong> gi\u00e0 adibito all\u2019ex sede dell\u2019Istituto Previdenziale e sito in Cosenza alla via Isonzo&#8221;. Lo annuncia con una nota l&#8217;Azienda Sanitaria Provinciale di Cosenza.<\/p>\n<p>&#8220;L\u2019acquisto rientra nel programma di una <strong>razionalizzazione dei servizi sanitari<\/strong> della citt\u00e0 di Cosenza e nel<strong> contenimento dei fitti passivi,<\/strong> con notevole risparmio e pertanto con possibilit\u00e0 di ulteriori risorse da ridistribuire nei servizi sanitari.<\/p>\n<p>La decisione di <strong>tagliare le spese dei fitti,<\/strong> \u00e8 figlia della moderna impostazione impressa dal management. Centralizzare in un luogo fisico i servizi, non pu\u00f2 che migliorare la fruizione degli stessi, offerti ai cittadini\/utenti, atteso che lo stabile sar\u00e0 finalizzato esclusivamente all\u2019offerta delle prestazioni sanitarie e pi\u00f9 precisamente, ad un Servizio di Diagnostica avanzata con tecnologie di ultimissima generazione, al fine di implementare i servizi sanitari nell\u2019ottica di quella normalizzazione del nostro Sistema Sanitario Regionale, voluta fortemente dal Presidente Roberto Occhiuto e condivisa dalla nuova Governance dell\u2019Azienda Sanitaria Provinciale di Cosenza.<\/p>\n<p>Dopo anni di attesa, la decisione assunta dalla Azienda stessa, rappresenta <strong>una novit\u00e0 assoluta<\/strong> che aggiunge risorse alla politica sanitaria della provincia cosentina. Si tratta della pi\u00f9 importante operazione di razionalizzazione delle spese mai fatta dall\u2019Azienda Sanitaria. Una scelta di campo netta che segna il passaggio nella nuova era&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Questa mattina alle ore 10.30, dinanzi al Notaio Italo Alessio Scornajenchi, l\u2019Asp di Cosenza in persona del suo Direttore Generale Dott. Antonio Graziano, ha acquistato dall\u2019Inps, rappresentata dal Direttore Regionale dott. Giuseppe Greco, un prestigioso stabile gi\u00e0 adibito all\u2019ex sede dell\u2019Istituto Previdenziale e sito in Cosenza alla via Isonzo&#8221;. Lo annuncia con una [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":169575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-214868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=214868"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/214868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169575"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=214868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=214868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=214868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}