{"id":215237,"date":"2023-10-31T19:12:10","date_gmt":"2023-10-31T18:12:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215237"},"modified":"2023-10-31T19:12:10","modified_gmt":"2023-10-31T18:12:10","slug":"cosenza-terapia-intensiva-pediatrica-rischia-di-chiudere-il-sindaco-pronti-a-lottare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-terapia-intensiva-pediatrica-rischia-di-chiudere-il-sindaco-pronti-a-lottare\/","title":{"rendered":"Cosenza, terapia intensiva pediatrica rischia di chiudere. Il sindaco: \u00abpronti a lottare\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Terapia intensiva pediatrica a rischio chiusura all&#8217;Ospedale di Cosenza: dura presa di posizione del<strong> sindaco Franz Caruso<\/strong> \u201cSiamo pronti ad alzare le barricate e a contrastare con tutti gli strumenti a nostra disposizione il tentativo di perpetrare l&#8217;ennesimo scippo a danno dell&#8217;Azienda Ospedaliera di Cosenza\u201d. Lo afferma il Sindaco Franz Caruso, non appena appresa la notizia dell&#8217;eventuale <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/lannunziata-di-cosenza-perde-la-terapia-intensiva-pediatrica-di-natale-vergognoso\" target=\"_blank\" rel=\"noopener\">soppressione dei posti letto<\/a><\/strong> <strong>della terapia intensiva pediatrica all&#8217;Ospedale di Cosenza,<\/strong> prevista dal decreto di riorganizzazione della rete ospedaliera in Calabria.<\/p>\n<h3><strong>Caruso: &#8220;idea scellerata e inaccettabile&#8221;<\/strong><\/h3>\n<p>\u201cLa nostra presa di posizione \u2013 ha sottolineato Franz Caruso \u2013 non nasce sotto spinte campanilistiche, atteso che la paventata chiusura dei posti letto di rianimazione pediatrica a Cosenza coinciderebbe con l&#8217;attivazione di cinque posti letto all&#8217;Azienda Ospedaliera Unica \u201cDulbecco\u201d di Catanzaro, ma soprattutto perch\u00e9 sarebbe una soluzione inaccettabile, nella misura in cui<strong> tutto si giocherebbe sulla pelle di piccoli pazienti<\/strong> il cui diritto alla salute dovrebbe, invece, essere universalmente garantito sopra ogni cosa e tenuto ben distante da calcoli di natura eminentemente ragionieristica. Una decisione di questa portata, laddove si dovesse malauguratamente verificare, sarebbe<strong> un errore imperdonabile<\/strong> e che la citt\u00e0 di Cosenza non potrebbe accettare supinamente.<\/p>\n<p>E&#8217; bene che lo sappia la Regione, il suo Presidente e chi si appresta a varare un piano di riorganizzazione della rete ospedaliera che non pu\u00f2 partire da questi presupposti assurdi e che non hanno il bench\u00e9 minimo fondamento.<\/p>\n<p>Rivolgo, pertanto \u2013 ha concluso Franz Caruso \u2013 un <strong>pressante appello alla mobilitazione<\/strong> affinch\u00e9 questa idea scellerata venga messa da parte e si torni alla ragione e a far prevalere il buon senso. Sarebbe esercizio vacuo aprire dibattiti sulla necessit\u00e0 di garantire alla citt\u00e0 di Cosenza e ad un territorio provinciale molto pi\u00f9 vasto un hub ospedaliero moderno ed efficace, punto di riferimento fondamentale della vita delle nostre comunit\u00e0, <strong>se poi si mettono a rischio funzioni essenziali e vitali<\/strong> come la terapia intensiva pediatrica. L\u2019obiettivo \u00e8 creare le condizioni perch\u00e9 nella nostra citt\u00e0 e nella nostra provincia venga assicurata una sanit\u00e0 di qualit\u00e0 che non pu\u00f2 non partire dal garantire anzitutto il diritto alla salute dei bambini\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Terapia intensiva pediatrica a rischio chiusura all&#8217;Ospedale di Cosenza: dura presa di posizione del sindaco Franz Caruso \u201cSiamo pronti ad alzare le barricate e a contrastare con tutti gli strumenti a nostra disposizione il tentativo di perpetrare l&#8217;ennesimo scippo a danno dell&#8217;Azienda Ospedaliera di Cosenza\u201d. Lo afferma il Sindaco Franz Caruso, non appena [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":215239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-215237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215237"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/215239"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}